
{"id":108068,"date":"2021-05-28T00:06:00","date_gmt":"2021-05-28T03:06:00","guid":{"rendered":"https:\/\/www.largadoemguarapari.com.br\/13largado\/?p=108068"},"modified":"2021-05-25T10:11:19","modified_gmt":"2021-05-25T13:11:19","slug":"brihadisvara-temple","status":"publish","type":"post","link":"https:\/\/www.largadoemguarapari.com.br\/13largado\/brihadisvara-temple\/","title":{"rendered":"Brihadisvara Temple"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-content\/uploads\/2021\/05\/190542408_1077708519419152_515412352788890_n.jpg\" alt=\"\" class=\"wp-image-108069\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Templo de Brihadisvara, um templo hindu em Thanjavur, \u00cdndia <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\uddee\ud83c\uddf3\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tb3\/1\/16\/1f1ee_1f1f3.png\"\/>! Brihadisvara \u00e9 um templo hindu exemplar do estilo dravidiano de arquitetura religiosa e o primeiro grande templo do granito do mundo. Ainda hoje \u00e9 o maior templo da \u00cdndia. Foi constru\u00eddo pelo rei Chola Rajaraja Chola I entre 1003 e 1010.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">O edif\u00edcio, dedicado a Shiva-Rudra, \u00e9 rodeado por dois compartimentos retangulares, e \u00e9 ele pr\u00f3prio feito de blocos de granito. Uma rampa de terra de mais de 6 km foi necess\u00e1ria para construir o bolbo monol\u00edtico at\u00e9 ser colocado no topo do vim\u00e2na, uma t\u00e9cnica tamb\u00e9m usada no Antigo Egito <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\uddea\ud83c\uddec\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t40\/1\/16\/1f1ea_1f1ec.png\"\/>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em 2010 o templo completou um mil\u00e9nio, tendo na ocasi\u00e3o servido de palco a numerosas festividades e comemora\u00e7\u00f5es. Ele faz parte do s\u00edtio classificado pela UNESCO como Patrim\u00f3nio da Humanidade denominado &#8220;Grandes Templos Vivos de Chola&#8221;. <a href=\"https:\/\/www.facebook.com\/hashtag\/geografiageral?__eep__=6&amp;__cft__[0]=AZUCJjUwR_o4COoVNRp8fvoUmtyC59i7ZADX2dPUH7e7GmTCxOmar_rpUUVbrc-eHABPYGAKz9D1-UTFYZ5msYjMWeb5LtQehARNtB6ziyYtd-uXqJ6006EEASiZg3dqb125DBRD4IPp-_pfN-sUNWKWYFR6EaY5ekDX2Qdekd1fk5trTgrlbhVSUc5B43UOSxE&amp;__tn__=*NK-R\">#geografiageral<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/educadf?__eep__=6&amp;__cft__[0]=AZUCJjUwR_o4COoVNRp8fvoUmtyC59i7ZADX2dPUH7e7GmTCxOmar_rpUUVbrc-eHABPYGAKz9D1-UTFYZ5msYjMWeb5LtQehARNtB6ziyYtd-uXqJ6006EEASiZg3dqb125DBRD4IPp-_pfN-sUNWKWYFR6EaY5ekDX2Qdekd1fk5trTgrlbhVSUc5B43UOSxE&amp;__tn__=*NK-R\">#educadf<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/history?__eep__=6&amp;__cft__[0]=AZUCJjUwR_o4COoVNRp8fvoUmtyC59i7ZADX2dPUH7e7GmTCxOmar_rpUUVbrc-eHABPYGAKz9D1-UTFYZ5msYjMWeb5LtQehARNtB6ziyYtd-uXqJ6006EEASiZg3dqb125DBRD4IPp-_pfN-sUNWKWYFR6EaY5ekDX2Qdekd1fk5trTgrlbhVSUc5B43UOSxE&amp;__tn__=*NK-R\">#history<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/india?__eep__=6&amp;__cft__[0]=AZUCJjUwR_o4COoVNRp8fvoUmtyC59i7ZADX2dPUH7e7GmTCxOmar_rpUUVbrc-eHABPYGAKz9D1-UTFYZ5msYjMWeb5LtQehARNtB6ziyYtd-uXqJ6006EEASiZg3dqb125DBRD4IPp-_pfN-sUNWKWYFR6EaY5ekDX2Qdekd1fk5trTgrlbhVSUc5B43UOSxE&amp;__tn__=*NK-R\">#india<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Templo de Brihadisvara, um templo hindu em Thanjavur, \u00cdndia ! Brihadisvara \u00e9 um templo hindu exemplar do estilo dravidiano de arquitetura religiosa e o primeiro grande templo do granito do mundo. Ainda hoje \u00e9 o maior templo da \u00cdndia. Foi constru\u00eddo pelo rei Chola Rajaraja Chola I entre 1003 e 1010.<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-108068","post","type-post","status-publish","format-standard","hentry","category-engracadas"],"_links":{"self":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts\/108068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/comments?post=108068"}],"version-history":[{"count":1,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts\/108068\/revisions"}],"predecessor-version":[{"id":108070,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts\/108068\/revisions\/108070"}],"wp:attachment":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/media?parent=108068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/categories?post=108068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/tags?post=108068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}