
{"id":110179,"date":"2021-07-29T00:07:00","date_gmt":"2021-07-29T03:07:00","guid":{"rendered":"https:\/\/www.largadoemguarapari.com.br\/13largado\/?p=110179"},"modified":"2021-07-29T01:17:48","modified_gmt":"2021-07-29T04:17:48","slug":"e-velha-mas-e-boa-2027","status":"publish","type":"post","link":"https:\/\/www.largadoemguarapari.com.br\/13largado\/e-velha-mas-e-boa-2027\/","title":{"rendered":"\u00c9 VELHA, MAS \u00c9 BOA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Um homem e uma mulher se envolvem num acidente de grandes propor\u00e7\u00f5es:\u00a0os carros s\u00e3o inteiramente destru\u00eddos, mas, por sorte, nenhum dos dois fica ferido. \u00a0 <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0 Depois de conseguirem sair do que restou dos carros, a mulher diz: \u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> \u2014 Olha s\u00f3! Voc\u00ea, um homem, e eu, uma mulher, sa\u00edmos ilesos de um acidentes desses! S\u00f3 pode ser um sinal de Deus! Ele est\u00e1 nos dando uma oportunidade para nos conhecermos e ficarmos juntos para o resto da vida! \u00a0 <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2014 Concordo \u2014 responde o homem \u2014 Isso deve ser um sinal divino! \u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> A mulher continua: \u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> \u2014 E olha s\u00f3, um outro milagre: meu carro ficou totalmente destru\u00eddo, mas essa garrafa de u\u00edsque n\u00e3o quebrou! Deve ser outro sinal. Vamos beber e comemorar esta sorte. \u00a0 E ela entrega a garrafa ao homem. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ele concorda, abre a garrafa,\u00a0toma alguns goles diretamente do gargalo e devolve a garrafa \u00e0 mulher. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ela a pega, coloca a tampa de volta, e a devolve ao homem. \u00a0 <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ele n\u00e3o entende o gesto e pergunta: \u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> \u2014 Voc\u00ea n\u00e3o vai tomar? \u00a0 <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2014 N\u00e3o! Eu vou esperar a pol\u00edcia chegar com o baf\u00f4metro&#8230;<\/p>\n\n\n\n<div style=\"height:24px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Um homem e uma mulher se envolvem num acidente de grandes propor\u00e7\u00f5es:\u00a0os carros s\u00e3o inteiramente destru\u00eddos, mas, por sorte, nenhum dos dois fica ferido. \u00a0 \u00a0 Depois de conseguirem sair do que restou dos carros, a mulher diz: \u00a0 \u2014 Olha s\u00f3! Voc\u00ea, um homem, e eu, uma mulher, sa\u00edmos ilesos de um acidentes desses! [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-110179","post","type-post","status-publish","format-standard","hentry","category-engracadas"],"_links":{"self":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts\/110179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/comments?post=110179"}],"version-history":[{"count":2,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts\/110179\/revisions"}],"predecessor-version":[{"id":110227,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts\/110179\/revisions\/110227"}],"wp:attachment":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/media?parent=110179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/categories?post=110179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/tags?post=110179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}