
{"id":115661,"date":"2021-12-30T14:30:48","date_gmt":"2021-12-30T17:30:48","guid":{"rendered":"https:\/\/www.largadoemguarapari.com.br\/13largado\/?p=115661"},"modified":"2021-12-30T14:34:45","modified_gmt":"2021-12-30T17:34:45","slug":"frase-do-dia-2656","status":"publish","type":"post","link":"https:\/\/www.largadoemguarapari.com.br\/13largado\/frase-do-dia-2656\/","title":{"rendered":"FRASE DO DIA"},"content":{"rendered":"\n<h1 class=\"has-text-align-left wp-block-heading\" style=\"font-size:30px\">&#8220;Na Bahia, 136 cidades est\u00e3o em estado de emerg\u00eancia. Mais de 470 mil pessoas est\u00e3o na rua da amargura. O governador baiano, at\u00f4nito, faz de conta que n\u00e3o sabia que todo o ano as chuvas de ver\u00e3o fazem isso na Bahia. Agora j\u00e1 est\u00e1 nas redes o\u00a0<strong>abracebahia@org.br.<\/strong><\/h1>\n\n\n\n<div style=\"height:11px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"font-size:25px\">Que me desculpem os baianos, gente boa e manemolente que n\u00e3o merece isso&#8230; Isso que eu me refiro: a trag\u00e9dia e os governantes que tem. Sinto muito, de minha parte, n\u00e3o mando um centavo. J\u00e1 sei o que os mandachuvas baianos fazem com a grana que chega por l\u00e1. Al\u00e9m disso, o Bolsonaro \u2013 mesmo de f\u00e9rias &#8211; j\u00e1 est\u00e1 providenciando o aux\u00edlio necess\u00e1rio ao povo baiano.&#8221;<\/h2>\n\n\n\n<div style=\"height:27px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Sergio A O Siqueira<\/strong><\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Na Bahia, 136 cidades est\u00e3o em estado de emerg\u00eancia. Mais de 470 mil pessoas est\u00e3o na rua da amargura. O governador baiano, at\u00f4nito, faz de conta que n\u00e3o sabia que todo o ano as chuvas de ver\u00e3o fazem isso na Bahia. Agora j\u00e1 est\u00e1 nas redes o\u00a0abracebahia@org.br. Que me desculpem os baianos, gente boa e [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-115661","post","type-post","status-publish","format-standard","hentry","category-frase-do-dia"],"_links":{"self":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts\/115661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/comments?post=115661"}],"version-history":[{"count":9,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts\/115661\/revisions"}],"predecessor-version":[{"id":115671,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts\/115661\/revisions\/115671"}],"wp:attachment":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/media?parent=115661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/categories?post=115661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/tags?post=115661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}