
{"id":120651,"date":"2022-07-11T10:07:36","date_gmt":"2022-07-11T13:07:36","guid":{"rendered":"https:\/\/www.largadoemguarapari.com.br\/13largado\/?p=120651"},"modified":"2022-07-11T11:57:58","modified_gmt":"2022-07-11T14:57:58","slug":"cronologia-do-golpe","status":"publish","type":"post","link":"https:\/\/www.largadoemguarapari.com.br\/13largado\/cronologia-do-golpe\/","title":{"rendered":"CRONOLOGIA DO GOLPE"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">26 DE ABRIL DE 2016 &#8211; O caub\u00f3i de gado fantasma, Renan Calheiros, iniciou o golpe que vem transformando a democracia brasileira numa ditadura de toga e colarinho branco. Isso come\u00e7ou no Senado Federal, em 26 de abril de 2016, com a aprova\u00e7\u00e3o projeto, que modificou a lei dos crimes de abuso de autoridade, por 54 votos favor\u00e1veis e 19 contr\u00e1rios.<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">1\u00ba DE JANEIRO DE 2019 \u2013 Assim que tomou posse no cargo de Presidente da Rep\u00fablica, Bolsonaro passou a ser alvejado pelos cortes\u00e3os donos dos mais ricos cargos de confian\u00e7a da m\u00e1quina p\u00fablica brasileira: os \u00e1rbitros engolidores de apito da Corte das Divinas Togas, sede das maquina\u00e7\u00f5es Lul@lcaponistas.<\/p>\n\n\n\n<!--more-->\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">16 DE ABRIL DE 2020 \u2013 Quatro anos depois, sob a batuta do desafinado maestro Gilmuar do Bacalhau, o Supremo Tribunal Federal fragilizou propositadamente o governo central e estendeu o controle da Pandemia para 27 governadores e 5.569 prefeitos, como se n\u00e3o soubessem que pelo velho e conhecido brocardo jur\u00eddico de que \u2018em cada cabe\u00e7a h\u00e1 uma senten\u00e7a\u2019 \u2013 adviria inevitavelmente o caos sanit\u00e1rio que o Brasil enfrenta at\u00e9 hoje.<\/p>\n\n\n\n<div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">29 DE ABRIL DE 2020 \u2013 E foi ent\u00e3o que Aleixand\u00e3o, o xerif\u00f3ide da Corte das Divinas Togas, come\u00e7ou a p\u00f4r as manguinhas de fora. Com um caneta\u00e7o vermelho, riscou do mapa a nomea\u00e7\u00e3o de Alexandre Ramagem para a chefia da Pol\u00edcia Federal, feita pela caneta azul do presidente da Rep\u00fablica.<\/p>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">03 de FEVEREIRO DE 2021 \u2013 Aras, o Augusto mensageiro do Planalto, chegou para dar o golpe de miseric\u00f3rdia na Opera\u00e7\u00e3o Lava-Jato. E deu. O Pai dos Filhos do Capit\u00e3o, naquela data, celebrou o feito dizendo que n\u00e3o precisava da Lava-Jato, porque no seu governo n\u00e3o havia corrup\u00e7\u00e3o. Mal sabia o quanto precisaria logo depois de uma Lava-Jato mais forte ainda que aquela que foi desfeita.<\/p>\n\n\n\n<div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">08 DE MAR\u00c7O DE 2021 \u2013 Eis a data solene do grande golpe: Fachinews anulou de uma sentada s\u00f3 de sua caneta suprema todas as condena\u00e7\u00f5es de Lul@alcapone. Descondenou, mas n\u00e3o conseguiu inocentar, aquele que roubou e deixou roubar; aquele que estava na cadeia por corrup\u00e7\u00e3o ativa, passiva e lavagem contumaz de dinheiro. Devolveu-lhe os chamados \u2018direitos pol\u00edticos\u2019 e tornou-o eleg\u00edvel outra vez, para voltar \u00e0 cena do crime. Voltar e humilhar a brava gente brasileira que tem o direito e a obriga\u00e7\u00e3o de votar numa elei\u00e7\u00e3o que tem um delinquente que escapou da cadeia como candidato \u00e0 Presid\u00eancia da Rep\u00fablica. <\/p>\n\n\n\n<div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">14 DE JUNHO DE 2022 \u2013 Fachinews v\u00ea e celebra a elei\u00e7\u00e3o de Aleixand\u00e3o para a presid\u00eancia do puxadinho da Torre das Togas, a Corte Leitereira.<\/p>\n\n\n\n<div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">DESDE JANEIRO DE 2003&#8230;Tudo, na verdade, come\u00e7ou a ser um a grande golpe na democracia brasileira, quando Lul@lcapone gradativa, sistem\u00e1tica e maquiavelicamente come\u00e7ou a aparelhar a m\u00e1quina p\u00fablica brasileira, desde que subiu a rampa do Pal\u00e1cio do Planalto, pela primeira vez, no fat\u00eddico dia 1\u00b0 janeiro de 2003. N\u00e3o h\u00e1, hoje, nesse pa\u00eds, uma institui\u00e7\u00e3o p\u00fablica que n\u00e3o tenha um balc\u00e3o de lavadores de dinheiro e operadores a servi\u00e7o daquele que rouba e deixa roubar. A come\u00e7ar, pela Torre das Divinas Togas.<\/p>\n\n\n\n<div style=\"height:11px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Sanat\u00f3rio da Not\u00edcia<\/p><\/blockquote>\n\n\n\n<div style=\"height:18px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>26 DE ABRIL DE 2016 &#8211; O caub\u00f3i de gado fantasma, Renan Calheiros, iniciou o golpe que vem transformando a democracia brasileira numa ditadura de toga e colarinho branco. Isso come\u00e7ou no Senado Federal, em 26 de abril de 2016, com a aprova\u00e7\u00e3o projeto, que modificou a lei dos crimes de abuso de autoridade, por [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-120651","post","type-post","status-publish","format-standard","hentry","category-materia-dos-outros"],"_links":{"self":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts\/120651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/comments?post=120651"}],"version-history":[{"count":6,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts\/120651\/revisions"}],"predecessor-version":[{"id":120660,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts\/120651\/revisions\/120660"}],"wp:attachment":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/media?parent=120651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/categories?post=120651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/tags?post=120651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}