
{"id":130153,"date":"2023-08-28T20:47:06","date_gmt":"2023-08-28T23:47:06","guid":{"rendered":"https:\/\/www.largadoemguarapari.com.br\/13largado\/?p=130153"},"modified":"2023-08-28T20:47:06","modified_gmt":"2023-08-28T23:47:06","slug":"noticias-da-noite","status":"publish","type":"post","link":"https:\/\/www.largadoemguarapari.com.br\/13largado\/noticias-da-noite\/","title":{"rendered":"NOT\u00cdCIAS DA NOITE"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u2705\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t33\/1\/16\/2705.png\"\/> NOT\u00cdCIAS DO DIA &#8211; ANO 7 n\u00b0 2473<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dia 28 de Agosto de 2023, Segunda-Feira<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">DATAS COMEMORATIVAS<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dia da Avicultura<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dia <a><\/a>dos Banc\u00e1rios<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dia Nacional do Voluntariado<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dia Nacional de Combate e Preven\u00e7\u00e3o ao Escalpelamento<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">TEMPERATURA E INDICADORES FINANCEIROS<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u26c5\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t9f\/1\/16\/26c5.png\"\/> M\u00edn 24\u00b0 M\u00e1x 35\u00b0 (Boa Vista-RR)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udcb5\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tdf\/1\/16\/1f4b5.png\"\/> D\u00f3lar Com: <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u2b07\ufe0f\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t20\/1\/16\/2b07.png\"\/> 0,09% R$ 4,87<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udcb6\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t60\/1\/16\/1f4b6.png\"\/>Euro: <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u2b07\ufe0f\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t20\/1\/16\/2b07.png\"\/> 0,11% R$ 5,26<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udcca\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/taa\/1\/16\/1f4ca.png\"\/> Ibovespa: <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u2b07\ufe0f\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t20\/1\/16\/2b07.png\"\/> 1,02% 115.837 pts<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83e\ude99\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/td9\/1\/16\/1fa99.png\"\/> Bitcoin: <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u2b06\ufe0f\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t9f\/1\/16\/2b06.png\"\/> 0,21% R$ 128.169,58<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udcb2\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t5c\/1\/16\/1f4b2.png\"\/>IPCA <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u2b06\ufe0f\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t9f\/1\/16\/2b06.png\"\/> 0,12% Julho 2023<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udcb2\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t5c\/1\/16\/1f4b2.png\"\/>SELIC <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u2b06\ufe0f\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t9f\/1\/16\/2b06.png\"\/> 13,25% 02 de Agosto de 2023<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udfe8\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t2\/1\/16\/1f7e8.png\"\/> Ouro (grama): <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u2b07\ufe0f\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t20\/1\/16\/2b07.png\"\/> R$ 304,36<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t9\/1\/16\/1f1e7_1f1f7.png\" alt=\"\ud83c\udde7\ud83c\uddf7\"\/><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/td6\/1\/16\/1f4f0.png\" alt=\"\ud83d\udcf0\"\/> NOT\u00cdCIAS NACIONAIS<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udc65\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t8b\/1\/16\/1f465.png\"\/> Grupo da CPI do MST busca f\u00f4lego para driblar esvaziamento da comiss\u00e3o e desgastar governo; oposi\u00e7\u00e3o obstruiu vota\u00e7\u00e3o de requerimentos e trabalhou para reverter maioria conquistada pelos governistas ap\u00f3s movimento do Centr\u00e3o<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u2696\ufe0f\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/ta\/1\/16\/2696.png\"\/> Dias Toffoli diz que seguran\u00e7a cibern\u00e9tica \u00e9 \u2018tema urgente\u2019 no Brasil; de acordo com o ministro do STF, falta uma pol\u00edtica clara para lidar com o assunto<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\ude94\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t69\/1\/16\/1f694.png\"\/> Pol\u00edcia Federal apreende caminh\u00e3o com quase duas toneladas de droga no Paran\u00e1; um suspeito foi preso em flagrante pelo crime de tr\u00e1fico internacional de drogas e levado para a Delegacia de Pol\u00edcia Federal em Foz do Igua\u00e7u<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\ude94\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t69\/1\/16\/1f694.png\"\/> Pol\u00edcia Federal prende duas pessoas pelo crime de descaminho em C\u00e9u Azul (PR); presos estavam em um \u00f4nibus de turismo quando foram abordadas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\ude94\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t69\/1\/16\/1f694.png\"\/> PM apreende 500 pessoas por arrast\u00f5es em show de Alok no Rio; soco ingl\u00eas, canivetes, tesouras, cortadores de unha, chave de fenda, faca, estilete, fac\u00e3o e outros objetos foram apreendidos nos pontos de bloqueio da pol\u00edcia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udc65\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t8b\/1\/16\/1f465.png\"\/><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udcf2\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/td8\/1\/16\/1f4f2.png\"\/> Golpe da portabilidade: criminosos roubam linha de celular e passam a acessar redes sociais da v\u00edtima; desde abril, cliente que pede a portabilidade do n\u00famero para outra operadora recebe uma mensagem de confirma\u00e7\u00e3o<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udcb2\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t5c\/1\/16\/1f4b2.png\"\/><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\ude98\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t6d\/1\/16\/1f698.png\"\/> Navio chin\u00eas com mais de 2.700 carros el\u00e9tricos chega a Vila Velha nesta ter\u00e7a-feira (29); navio partiu da China em 18 de julho rumo ao Brasil com carros el\u00e9tricos de alto padr\u00e3o; o destino da embarca\u00e7\u00e3o \u00e9 o Terminal Portu\u00e1rio de Vila Velha (ES)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udcb2\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t5c\/1\/16\/1f4b2.png\"\/>Pequeno neg\u00f3cio eleva arrecada\u00e7\u00e3o do Simples em mais de 7% neste ano; segundo a Receita Federal, desde o primeiro ano p\u00f3s-pandemia, a arrecada\u00e7\u00e3o das micro e pequenas empresas tem trajet\u00f3ria crescente<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udc65\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t8b\/1\/16\/1f465.png\"\/> SP Ocean Week 2023 chama aten\u00e7\u00e3o para conhecimento dos mares; organiza\u00e7\u00e3o do evento ressalta que a discuss\u00e3o sobre o futuro dos mares \u00e9 importante para o pa\u00eds, uma vez que a quest\u00e3o dos oceanos \u00e9 inadi\u00e1vel porque o mar est\u00e1 \u201ccansado\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CI\u00caNCIA e TECNOLOGIA<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udc65\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t8b\/1\/16\/1f465.png\"\/> Pesquisadores brasileiros dominam t\u00e9cnica para sequenciar DNA antigo; trabalho de Tiago Ferraz e Andr\u00e9 Menezes Strauss foi baseado na extra\u00e7\u00e3o do genoma de 34 amostras, com at\u00e9 10 mil anos de idade, de diferentes s\u00edtios arqueol\u00f3gicos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udcf2\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/td8\/1\/16\/1f4f2.png\"\/> De olho no futuro: Brasil busca acelerar implanta\u00e7\u00e3o e ades\u00e3o ao 5G enquanto fica aqu\u00e9m de outros pa\u00edses; diferente de diversos pa\u00edses no mundo, Brasil ainda demora para se conectar com esta tecnologia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\ude80\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tc6\/1\/16\/1f680.png\"\/> Astronautas russo e americano se abra\u00e7am com chegada de nave Dragon \u00e0 Esta\u00e7\u00e3o Espacial; quatro novos tripulantes, de nacionalidades diferentes, chegaram hoje depois de um dia de viagem e foram recebidos com festa<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ESPORTES<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u26bd\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/taf\/1\/16\/26bd.png\"\/> Campeonato Brasileiro<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00e9rie A, 21\u00aa rodada:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bragantino 2&#215;0 Cuiab\u00e1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Am\u00e9rica-MG 2&#215;1 S\u00e3o Paulo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Atl\u00e9tico-MG 2&#215;0 Santos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Botafogo 3&#215;0 Bahia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Athletico-PR 2&#215;2 Fluminense<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fortaleza 3&#215;1 Coritiba<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Palmeiras 1&#215;0 Vasco<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gr\u00eamio 3&#215;0 Cruzeiro<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00e9rie B, 25\u00aa rodada:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chapecoense 0x0 Ava\u00ed<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Atl\u00e9tico-GO 0x0 Vit\u00f3ria<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udfd0\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t57\/1\/16\/1f3d0.png\"\/> V\u00f4lei: Brasil vence Chile e segue 100% no Sul-Americano masculino; destaque da estreia, Felipe Roque come\u00e7a no lugar de Alan e corresponde \u00e0 oportunidade; sele\u00e7\u00e3o soma agora duas vit\u00f3rias, sem perder sets<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udfce\ufe0f\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t6d\/1\/16\/1f3ce.png\"\/> Verstappen vence ca\u00f3tico GP da Holanda e iguala recorde de Vettel na F\u00f3rmula 1; holand\u00eas chega ao nono triunfo consecutivo na F1 2023 em corrida paralisada por chuva, com Alonso e Gasly no p\u00f3dio; Zhou, Leclerc e Sargeant abandonam<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udfcd\ufe0f\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tec\/1\/16\/1f3cd.png\"\/> Pilotos morrem em acidente grav\u00edssimo na prova do Moto 1000 GP no Paran\u00e1; \u00c9rico Ver\u00edssimo, de 38 anos, e Andr\u00e9 Ver\u00edssimo Cardoso, de 42 anos, foram atendidos pelos m\u00e9dicos com vida, mas n\u00e3o resistiram aos ferimentos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udf0d\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t3f\/1\/16\/1f30d.png\"\/><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udcf0\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/td6\/1\/16\/1f4f0.png\"\/> NOT\u00cdCIAS INTERNACIONAIS<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\uddf7\ud83c\uddfa\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t92\/1\/16\/1f1f7_1f1fa.png\"\/> R\u00fassia diz que testes gen\u00e9ticos confirmam morte de Prigozhin; Yevgeny Prigozhin, chefe do grupo mercen\u00e1rio Wagner, estava entre as dez pessoas mortas em um acidente de avi\u00e3o na semana passada, perto de Moscou; h\u00e1 dois meses ele liderou motim contra militares russos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\uddf7\ud83c\uddfa\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t92\/1\/16\/1f1f7_1f1fa.png\"\/> R\u00fassia copia estrat\u00e9gia do grupo Wagner e envia presidi\u00e1rios para morrer na Ucr\u00e2nia; &#8220;\u00c9 como se estiv\u00e9ssemos sendo mandados para um abatedouro&#8221;, afirma ex-detento que foi ao campo de batalha<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udff4\udb40\udc67\udb40\udc62\udb40\udc73\udb40\udc63\udb40\udc74\udb40\udc7f\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t7f\/1\/16\/1f3f4_e0067_e0062_e0073_e0063_e0074_e007f.png\"\/> Esc\u00f3cia lan\u00e7a a maior opera\u00e7\u00e3o de buscas por monstro do lago Ness; investigadores v\u00e3o usar drones equipados com scanners t\u00e9rmicos, barcos com c\u00e2meras infravermelhas e um hidrofone para desvendar mist\u00e9rio<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\uddf8\ud83c\udde9\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t8c\/1\/16\/1f1f8_1f1e9.png\"\/> Ap\u00f3s quatro meses de confrontos, l\u00edder paramilitar apresenta roteiro para alcan\u00e7ar solu\u00e7\u00e3o pol\u00edtica no Sud\u00e3o; Dagalo disse na rede social X (antigo Twitter) que a guerra entre as FAR e o Ex\u00e9rcito \u00e9 \u2018um reflexo\u2019 de uma crise que o pa\u00eds arrasta h\u00e1 d\u00e9cadas e que deve ser enfrentada em suas ra\u00edzes<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\uddef\ud83c\uddf5\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t76\/1\/16\/1f1ef_1f1f5.png\"\/> Jap\u00e3o: \u00e1gua do mar de Fukushima tem radioatividade abaixo do limite; Minist\u00e9rio do Meio Ambiente informou que \u00e1gua da usina nuclear de Fukushima jogada no oceano \u00e9 segura para meio ambiente e sa\u00fade humana. Despejo provocou protestos no pa\u00eds<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udde6\ud83c\uddfa\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t72\/1\/16\/1f1e6_1f1fa.png\"\/> Tr\u00eas fuzileiros navais dos EUA morrem em acidente a\u00e9reo durante exerc\u00edcios na Austr\u00e1lia; ao todo, 23 soldados estavam a bordo da aeronave, que mistura caracter\u00edsticas de avi\u00e3o e helic\u00f3ptero; cinco est\u00e3o em estado grave<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\uddfa\ud83c\uddf8\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t93\/1\/16\/1f1fa_1f1f8.png\"\/> Ataque a tiros por &#8216;\u00f3dio racial&#8217; deixa tr\u00eas mortos nos Estados Unidos; autor do crime era um homem de cerca de 20 anos, que havia escrito manifestos detalhando &#8220;sua ideologia repugnante do \u00f3dio&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\uddfa\ud83c\uddf8\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t93\/1\/16\/1f1fa_1f1f8.png\"\/> Ex-fuzileiro que alega ter matado Bin Laden \u00e9 preso por agress\u00e3o nos Estados Unidos; Robert O\u2019Neill foi detido na \u00faltima quarta ap\u00f3s gravar um podcast; ele foi liberado depois de pagar fian\u00e7a de US$ 3,5 mil (cerca de R$ 17 mil, na cota\u00e7\u00e3o atual)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\uddfa\ud83c\uddf8\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t93\/1\/16\/1f1fa_1f1f8.png\"\/><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udf2a\ufe0f\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tfa\/1\/16\/1f32a.png\"\/> Tempestade tropical Idalia deve chegar \u00e0 Fl\u00f3rida como furac\u00e3o; segundo previs\u00e3o, ventos de quase 145 km por hora podem atingir a Fl\u00f3rida, na pr\u00f3xima quarta-feira (30)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udde8\ud83c\udde6\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/taa\/1\/16\/1f1e8_1f1e6.png\"\/> Ap\u00f3s quatro anos de libera\u00e7\u00e3o de maconha, Canad\u00e1 anuncia impacto negativo: \u201cn\u00famero de usu\u00e1rios aumentou consideravelmente\u201d; sendo assim, o governo canadense anunciou em setembro que ir\u00e1 revisar as consequ\u00eancias da legaliza\u00e7\u00e3o da maconha na sociedade, em especial a juventude e minorias ind\u00edgenas, para analisar seu efeito na economia e o com\u00e9rcio clandestino<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udde6\ud83c\uddf7\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t48\/1\/16\/1f1e6_1f1f7.png\"\/><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\uddea\ud83c\uddec\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t40\/1\/16\/1f1ea_1f1ec.png\"\/> Novos membros do Brics enfrentam infla\u00e7\u00e3o galopante, san\u00e7\u00f5es internacionais e dilema sobre ades\u00e3o ao bloco; em decis\u00e3o hist\u00f3rica, grupo, que representa 42% da popula\u00e7\u00e3o mundial, 23% do produto interno bruto (PIB) e 18% do com\u00e9rcio mundial, anunciou seis novos integrantes<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udf0d\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t3f\/1\/16\/1f30d.png\"\/> EVENTOS HIST\u00d3RICOS DO DIA<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; 1845: Publicada a primeira edi\u00e7\u00e3o da revista Scientific American<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; 1859: O Evento Carrington \u00e9 a mais forte tempestade geomagn\u00e9tica j\u00e1 registrada a atingir a Terra. O servi\u00e7o de tel\u00e9grafo el\u00e9trico \u00e9 amplamente interrompido<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; 1937: A Toyota Motor se torna uma empresa independente<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; 1941: Entra no ar o primeiro programa noticioso do r\u00e1dio brasileiro, Rep\u00f3rter Esso<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; 1963: Marcha sobre Washington: o reverendo Martin Luther King Jr faz seu discurso &#8220;Eu Tenho um Sonho&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; 1988: Desastre do show a\u00e9reo de Ramstein (Alemanha): tr\u00eas aeronaves da equipe de demonstra\u00e7\u00e3o da For\u00e7a A\u00e9rea Italiana colidem os destro\u00e7os caem sobre a multid\u00e3o. Setenta e cinco pessoas morrem e 346 ficam gravemente feridas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Essas s\u00e3o algumas not\u00edcias do dia <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u2705\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t33\/1\/16\/2705.png\"\/><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Autor: Roberto Vieira Filho <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udde7\ud83c\uddf7\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t9\/1\/16\/1f1e7_1f1f7.png\"\/><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udf0e\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tc0\/1\/16\/1f30e.png\"\/><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bom Dia!!! <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udc4d\ud83c\udffc\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tf8\/1\/16\/1f44d_1f3fc.png\"\/><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Compartilhado por <a href=\"https:\/\/www.facebook.com\/litoral24h?__cft__[0]=AZUm5-YAdUArs4BWUYp_Qq3rjkKLUQkisFVWy5ozCNKv8GM_oWJpGW9dKaEA2qx_oYcISpF-WaYeK7FzchxVyQGW_8TdJDNHT0AQJCeuMriHOu8dQuGYfPpuq0etZ788jXy3wXuBFWqqU4_SxbMfULhuUZqpyiQlnu9phw69iXDPJA&amp;__tn__=-]K-R\">Litoral 24h Online<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>NOT\u00cdCIAS DO DIA &#8211; ANO 7 n\u00b0 2473 Dia 28 de Agosto de 2023, Segunda-Feira DATAS COMEMORATIVAS Dia da Avicultura Dia dos Banc\u00e1rios Dia Nacional do Voluntariado Dia Nacional de Combate e Preven\u00e7\u00e3o ao Escalpelamento TEMPERATURA E INDICADORES FINANCEIROS M\u00edn 24\u00b0 M\u00e1x 35\u00b0 (Boa Vista-RR) D\u00f3lar Com: 0,09% R$ 4,87 Euro: 0,11% R$ 5,26 Ibovespa: [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-130153","post","type-post","status-publish","format-standard","hentry","category-engracadas"],"_links":{"self":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts\/130153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/comments?post=130153"}],"version-history":[{"count":1,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts\/130153\/revisions"}],"predecessor-version":[{"id":130154,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts\/130153\/revisions\/130154"}],"wp:attachment":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/media?parent=130153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/categories?post=130153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/tags?post=130153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}