
{"id":141530,"date":"2024-07-17T09:48:13","date_gmt":"2024-07-17T12:48:13","guid":{"rendered":"https:\/\/www.largadoemguarapari.com.br\/13largado\/?p=141530"},"modified":"2024-07-17T09:48:13","modified_gmt":"2024-07-17T12:48:13","slug":"noticias-do-dia-580","status":"publish","type":"post","link":"https:\/\/www.largadoemguarapari.com.br\/13largado\/noticias-do-dia-580\/","title":{"rendered":"NOT\u00cdCIAS DO DIA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u2705\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t33\/1\/16\/2705.png\"\/> NOT\u00cdCIAS DO DIA &#8211; ANO 8 n\u00b0 2797<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dia 17 de Julho de 2024, Quarta-Feira<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">DATAS COMEMORATIVAS<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dia de Prote\u00e7\u00e3o \u00e0s Florestas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dia <a><\/a>do Curupira<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dia do Submarinista<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dia Mundial do Emoji<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">TEMPERATURA E INDICADORES FINANCEIROS<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u26c5\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t9f\/1\/16\/26c5.png\"\/> M\u00edn 22\u00b0 M\u00e1x 27\u00b0 (Aracaju-SE)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udcb5\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tdf\/1\/16\/1f4b5.png\"\/> D\u00f3lar Com: <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u2b07\ufe0f\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t20\/1\/16\/2b07.png\"\/> 0,3% R$ 5,42<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udcb6\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t60\/1\/16\/1f4b6.png\"\/> Euro: <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u2b07\ufe0f\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t20\/1\/16\/2b07.png\"\/> 0,27% R$ 5,91<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udcca\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/taa\/1\/16\/1f4ca.png\"\/> Ibovespa: <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u2b07\ufe0f\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t20\/1\/16\/2b07.png\"\/> 0,16% 129.110 pts<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83e\ude99\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/td9\/1\/16\/1fa99.png\"\/> Bitcoin: <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u2b06\ufe0f\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t9f\/1\/16\/2b06.png\"\/> 1,3% R$ 353.576,78<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udcb2\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t5c\/1\/16\/1f4b2.png\"\/>IPCA <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u2b06\ufe0f\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t9f\/1\/16\/2b06.png\"\/> 0,21% Junho de 2024<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udcb2\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t5c\/1\/16\/1f4b2.png\"\/>SELIC <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u2b06\ufe0f\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t9f\/1\/16\/2b06.png\"\/> 10,5% 19 de Junho de 2024<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udfe8\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t2\/1\/16\/1f7e8.png\"\/> Ouro (grama): <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u2b06\ufe0f\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t9f\/1\/16\/2b06.png\"\/> R$ 431,48<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Colabore voluntariamente com o Informativo Di\u00e1rio &#8220;NOT\u00cdCIAS DO DIA &#8211;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t9\/1\/16\/1f1e7_1f1f7.png\" alt=\"\ud83c\udde7\ud83c\uddf7\"\/><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/td6\/1\/16\/1f4f0.png\" alt=\"\ud83d\udcf0\"\/> NOT\u00cdCIAS NACIONAIS<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udde7\ud83c\uddf7\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t9\/1\/16\/1f1e7_1f1f7.png\"\/><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udde6\ud83c\uddf7\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t48\/1\/16\/1f1e6_1f1f7.png\"\/> Embaixador do Brasil na Argentina reafirma a import\u00e2ncia da rela\u00e7\u00e3o bilateral entre pa\u00edses; Julio Bitelli destaca que parceria entre pa\u00edses transcende diverg\u00eancias entre l\u00edderes<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udc65\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t8b\/1\/16\/1f465.png\"\/> Governo federal buscar\u00e1 mediar conflitos ind\u00edgenas em Mato Grosso do Sul e no Paran\u00e1; primeira ocorr\u00eancia foi registrada no s\u00e1bado (13), em Douradina, a cerca de 195 quil\u00f4metros de Campo Grande; o segundo aconteceu na Terra Ind\u00edgena Dourados<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udc65\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t8b\/1\/16\/1f465.png\"\/> Pacheco anuncia pedido conjunto da Advocacia-Geral da Uni\u00e3o (AGU) e Senado por prorroga\u00e7\u00e3o do prazo de desonera\u00e7\u00e3o; pedido \u00e9 para que o projeto seja votado at\u00e9 30 de agosto; presidente do Senado disse, ainda, que vai criar uma comiss\u00e3o para analisar uma reforma no sistema de cobran\u00e7a de contribui\u00e7\u00e3o sobre a folha de pagamentos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udc65\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t8b\/1\/16\/1f465.png\"\/> Comiss\u00e3o do Senado analisa, nesta quarta-feira (17), projeto que prev\u00ea que ocupa\u00e7\u00e3o e invas\u00e3o de praias se torne crime; tema estar\u00e1 em discuss\u00e3o em sess\u00e3o com in\u00edcio previsto a partir das 11h<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u2696\ufe0f\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/ta\/1\/16\/2696.png\"\/> Procuradoria-Geral da Rep\u00fablica (PGR) denuncia mulher que escreveu com batom &#8220;Perdeu, man\u00e9&#8221; em est\u00e1tua no STF; D\u00e9bora dos Santos foi presa em mar\u00e7o de 2023, na 8\u00aa fase da Opera\u00e7\u00e3o Lesa P\u00e1tria, que investiga os atos de vandalismo do 8 de Janeiro<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\ude94\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t69\/1\/16\/1f694.png\"\/> Pol\u00edcia Federal combate migra\u00e7\u00e3o ilegal para os Estados Unidos e M\u00e9xico; foram cumpridos dois mandados de busca e apreens\u00e3o, expedidos pela 2\u00aa Vara Federal de Governador Valadares (MG), no mesmo munic\u00edpio<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\ude94\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t69\/1\/16\/1f694.png\"\/> Pol\u00edcia Federal reprime a\u00e7\u00f5es ilegais em terras ind\u00edgenas no Maranh\u00e3o; foram cumpridos mandados de pris\u00e3o preventiva contra exploradores de extra\u00e7\u00e3o e comercializa\u00e7\u00e3o ilegal de madeira<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\ude94\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t69\/1\/16\/1f694.png\"\/> Pol\u00edcia Federal deflagra Opera\u00e7\u00e3o Paper Land contra grupo que fraudou a Caixa Econ\u00f4mica Federal; foram cumpridos 18 mandados em 13 endere\u00e7os nas cidades goianas de Goi\u00e2nia, Aparecida de Goi\u00e2nia, Acre\u00fana e Rio Verde<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\ude94\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t69\/1\/16\/1f694.png\"\/> Pol\u00edcia Federal incinera mais de seis toneladas de drogas em S\u00e3o Paulo; boa parte se refere a uma grande apreens\u00e3o realizada este m\u00eas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\ude94\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t69\/1\/16\/1f694.png\"\/> Presidente de empresa de \u00f4nibus suspeita de elo com PCC \u00e9 preso em S\u00e3o Paulo; alvo da Opera\u00e7\u00e3o Fim da Linha, Ubiratan Ant\u00f4nio da Cunha est\u00e1 afastado do cargo e teve a pris\u00e3o decretada pela Justi\u00e7a<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udfe5\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t7b\/1\/16\/1f3e5.png\"\/> Prontu\u00e1rio digital de pacientes ser\u00e1 disponibilizado aos m\u00e9dicos; dados poder\u00e3o ser acessados, durante consulta, em qualquer ponto do Sistema \u00danico de Sa\u00fade em todo o pa\u00eds<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udca1\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t3c\/1\/16\/1f4a1.png\"\/>Ag\u00eancia Nacional de Energia El\u00e9trica (Aneel) aprova consulta p\u00fablica e marca leil\u00e3o de energia existente para dezembro; agentes de distribui\u00e7\u00e3o devem apresentar as \u201cdeclara\u00e7\u00f5es de necessidade\u201d no per\u00edodo de 28 de agosto a 4 de setembro de 2024<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udca6\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tc1\/1\/16\/1f4a6.png\"\/> Equatorial \u00e9 confirmada investidora estrat\u00e9gica da Sabesp; empresa cumpriu exig\u00eancias previstas na oferta p\u00fablica de a\u00e7\u00f5es para adquirir o bloco priorit\u00e1rio de 15% das a\u00e7\u00f5es da companhia de saneamento<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u2708\ufe0f\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tb6\/1\/16\/2708.png\"\/> Aeroporto de Porto Alegre reabrir\u00e1 parcialmente para voos em outubro; opera\u00e7\u00f5es de voos internacionais n\u00e3o ser\u00e3o retomadas durante a fase de funcionamento parcial que come\u00e7ar\u00e1 em outubro, diz chefe da Fraport no Brasil, Andreea Pal<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udf24\ufe0f\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t4d\/1\/16\/1f324.png\"\/> Clima deve variar em todo Brasil nesta quarta-feira (17); gradativamente o tempo volta a ficar est\u00e1vel sobre o Sul; umidade relativa do ar segue em n\u00edveis cr\u00edticos na regi\u00e3o central<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udcb5\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tdf\/1\/16\/1f4b5.png\"\/> D\u00f3lar tem queda moderada e fecha a R$ 5,42, apesar de ru\u00eddo fiscal dom\u00e9stico; real se beneficiou do recuo firme das taxas dos Treasuries; operadores afirmam que a cautela com a condu\u00e7\u00e3o das contas p\u00fablicas impede uma queda mais pronunciada da moeda americana<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udcb0\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t5a\/1\/16\/1f4b0.png\"\/> Ningu\u00e9m acerta as seis dezenas da Mega-Sena 2749, e pr\u00eamio vai a R$ 47 milh\u00f5es para o sorteio da pr\u00f3xima quinta-feira (18); n\u00fameros sorteados: 08, 25, 27, 38, 43 e 44<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CI\u00caNCIA e TECNOLOGIA<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udc65\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t8b\/1\/16\/1f465.png\"\/> Ci\u00eancia Pioneira apoiar\u00e1 pesquisadores durante tr\u00eas anos; edital contemplar\u00e1 at\u00e9 15 jovens cientistas com projetos inovadores em ci\u00eancias biom\u00e9dicas e sa\u00fade; h\u00e1 tamb\u00e9m possibilidade de apoio a projetos que tenham interface com ci\u00eancias exatas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83e\udd88\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t91\/1\/16\/1f988.png\"\/> F\u00f3ssil de tubar\u00e3o do tempo dos dinossauros resolve mist\u00e9rio de s\u00e9culos; dentes do Ptychodus, descobertos no s\u00e9culo XVIII, criaram especula\u00e7\u00f5es sobre as caracter\u00edsticas do animal<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udef0\ufe0f\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t58\/1\/16\/1f6f0.png\"\/><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udfe0\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tfa\/1\/16\/1f7e0.png\"\/> Telesc\u00f3pio Webb revela clima extremamente quente em an\u00e3s marrons c\u00f3smicas; atmosfera de an\u00e3s marrons conta com coquetel t\u00f3xico e nuvens de part\u00edcula de silicato pr\u00f3ximas a tempestades de areia do Saara<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ESPORTES<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u26bd\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/taf\/1\/16\/26bd.png\"\/> Campeonato Brasileiro<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00e9rie A, 17\u00aa rodada:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Juventude 1&#215;1 Atl\u00e9tico-MG<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Corinthians 2&#215;1 Crici\u00fama<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u26bd\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/taf\/1\/16\/26bd.png\"\/> Copa Sul-Americana<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">oitavas de final, jogo 1:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Huachipato (Chi) 2&#215;3 Racing (Uru)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rosario Central (Arg) 1&#215;0 Internacional (Bra)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u26bd\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/taf\/1\/16\/26bd.png\"\/><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udc64\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/ta\/1\/16\/1f464.png\"\/>Corinthians anuncia a contrata\u00e7\u00e3o do zagueiro Andr\u00e9 Ramalho, ex-PSV, da Holanda; zagueiro de 32 anos assinou contrato com o Tim\u00e3o at\u00e9 o fim de 2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u26bd\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/taf\/1\/16\/26bd.png\"\/><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udc64\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/ta\/1\/16\/1f464.png\"\/>Athletico-PR acerta ida de Bento para o Al-Nassr, de Cristiano Ronaldo, em negocia\u00e7\u00e3o de R$ 107 milh\u00f5es; goleiro n\u00e3o atua mais pelo Furac\u00e3o e viaja nesta semana para realizar exames m\u00e9dicos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\u26bd\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/taf\/1\/16\/26bd.png\"\/><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udc65\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t8b\/1\/16\/1f465.png\"\/> Federa\u00e7\u00e3o Francesa denunciar\u00e1 \u00e0 Fifa cantos racistas de argentinos; can\u00e7\u00f5es de cunho racista contra atletas da sele\u00e7\u00e3o francesa foram entoadas por jogadores da sele\u00e7\u00e3o argentina, durante transmiss\u00e3o ao vivo no Instagram da comemora\u00e7\u00e3o pela conquista da Copa Am\u00e9rica<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udfbe\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tce\/1\/16\/1f3be.png\"\/> Rafael Nadal aparece na lista de inscritos do US Open; tetracampe\u00e3o do torneio utilizou o ranking protegido e aparece como um dos nomes que possivelmente estar\u00e1 no Grand Slam<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udfc0\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tb8\/1\/16\/1f3c0.png\"\/> Nikola Jokic faz duplo-duplo, mas Austr\u00e1lia vence S\u00e9rvia em amistoso de basquete; armador australiano Patty Mills tem atua\u00e7\u00e3o de gala e anota 28 pontos em mais um jogo de prepara\u00e7\u00e3o para as Olimp\u00edadas de Paris<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udf0d\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t3f\/1\/16\/1f30d.png\"\/><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udcf0\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/td6\/1\/16\/1f4f0.png\"\/> NOT\u00cdCIAS INTERNACIONAIS<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\uddea\ud83c\uddfa\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tdd\/1\/16\/1f1ea_1f1fa.png\"\/> Roberta Metsola \u00e9 reeleita presidente do Parlamento Europeu; a maltesa foi reconduzida ao cargo at\u00e9 ao in\u00edcio de 2027, com uma maioria de 562 votos e por aclama\u00e7\u00e3o, na sess\u00e3o plen\u00e1ria da assembleia europeia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udded\ud83c\uddfa\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t20\/1\/16\/1f1ed_1f1fa.png\"\/> Guerra na Ucr\u00e2nia: Viktor Orb\u00e1n diz a l\u00edderes da Uni\u00e3o Europeia que Trump atuaria como mediador de paz; premi\u00ea da Hungria afirmou que republicano &#8220;faria isso se for reeleito e que n\u00e3o esperaria at\u00e9 a posse&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\uddeb\ud83c\uddf7\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t74\/1\/16\/1f1eb_1f1f7.png\"\/> Presidente franc\u00eas aceita a demiss\u00e3o do premi\u00ea Gabriel Attal; primeiro-ministro fica no cargo at\u00e9 forma\u00e7\u00e3o de novo governo; Jogos Ol\u00edmpicos de 2024 come\u00e7am em Paris na semana que vem<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udde9\ud83c\uddea\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t16\/1\/16\/1f1e9_1f1ea.png\"\/> Governo alem\u00e3o pro\u00edbe publica\u00e7\u00e3o da revista &#8220;Compact-Magazin&#8221;, considerada de extrema-direita; revista vende 40 mil exemplares mensais e incita ao \u00f3dio contra judeus; decis\u00e3o foi anunciada pela ministra do Interior, Nancy Faeser<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\uddee\ud83c\uddf1\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tb1\/1\/16\/1f1ee_1f1f1.png\"\/><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\uddf5\ud83c\uddf8\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t67\/1\/16\/1f1f5_1f1f8.png\"\/> For\u00e7as israelenses enfrentaram combatentes liderados pelo grupo terrorista Hamas em v\u00e1rias partes da Faixa de Gaza nesta ter\u00e7a-feira (16); autoridades de sa\u00fade palestinas disseram que pelo menos 50 pessoas foram mortas em bombardeios israelenses<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\uddee\ud83c\uddf1\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tb1\/1\/16\/1f1ee_1f1f1.png\"\/><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\uddf5\ud83c\uddf8\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t67\/1\/16\/1f1f5_1f1f8.png\"\/> Israel diz que metade da lideran\u00e7a da ala militar do grupo terrorista Hamas foi eliminada; aproximadamente 14 mil combatentes do grupo armado foram mortos ou capturados, ainda segundo os militares israelenses<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\uddee\ud83c\uddf1\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tb1\/1\/16\/1f1ee_1f1f1.png\"\/> Israel convocar\u00e1 judeus ultraortodoxos para as For\u00e7as Armadas; medida segue uma decis\u00e3o in\u00e9dita do Supremo Tribunal sobre o in\u00edcio do cumprimento do servi\u00e7o militar para jovens religiosos do g\u00eanero masculino<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\uddf0\ud83c\uddea\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tac\/1\/16\/1f1f0_1f1ea.png\"\/> Qu\u00eania volta a registrar protestos contra o presidente Ruto; uma pessoa morreu; onda de manifesta\u00e7\u00f5es come\u00e7ou com tentativa de aumento de impostos; governo recuou mas mobiliza\u00e7\u00e3o continua<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udde8\ud83c\uddee\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t59\/1\/16\/1f1e8_1f1ee.png\"\/> Costa do Marfim distribui primeiras doses de nova vacina contra a mal\u00e1ria; cerca de 250 mil crian\u00e7as com menos de dois anos devem ser as primeiras a serem vacinadas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\uddf9\ud83c\udded\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tf8\/1\/16\/1f1f9_1f1ed.png\"\/> Seis estrangeiros s\u00e3o encontrados mortos em hotel em Bangkok; premi\u00ea tailand\u00eas ordena investiga\u00e7\u00e3o ap\u00f3s incidente no luxuoso hotel Grand Hyatt Erawan<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\uddfa\ud83c\uddf8\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t93\/1\/16\/1f1fa_1f1f8.png\"\/><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udc65\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t8b\/1\/16\/1f465.png\"\/> Trump far\u00e1 primeiro ato de campanha no s\u00e1bado ap\u00f3s tentativa de assassinato; candidato e seu rec\u00e9m-anunciado companheiro de chapa para a vice-presid\u00eancia, J.D. Vance, \u201cv\u00e3o pronunciar discursos em um ato de campanha em Grand Rapids, Michigan, no s\u00e1bado (20), \u00e0s 17h locais\u201d, diz comunicado<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\uddf5\ud83c\uddea\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t71\/1\/16\/1f1f5_1f1ea.png\"\/> Pelo menos 25 morrem ap\u00f3s \u00f4nibus cair de penhasco no Peru; acidentes mortais com ve\u00edculos s\u00e3o comuns no pa\u00eds, onde muitos coletivos trafegam em estradas montanhosas prec\u00e1rias<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\uddfa\ud83c\uddf3\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/te\/1\/16\/1f1fa_1f1f3.png\"\/> ONU identifica eventos que v\u00e3o acelerar crise clim\u00e1tica mundial; programa das Na\u00e7\u00f5es Unidas para o Meio Ambiente usou novo sistema de previs\u00e3o de tend\u00eancias que concluiu que, neste novo contexto global, a velocidade das mudan\u00e7as \u00e9 surpreendente<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83c\udf0d\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t3f\/1\/16\/1f30d.png\"\/> EVENTOS HIST\u00d3RICOS DO DIA<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-1048: D\u00e2maso II \u00e9 eleito papa, mas morre 23 dias depois<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-1821: O Reino da Espanha cede o territ\u00f3rio da Fl\u00f3rida aos Estados Unidos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-1823: Imp\u00e9rio do Brasil: O imperador D. Pedro I aceita o pedido de demiss\u00e3o dos ministros, Jos\u00e9 Bonif\u00e1cio de Andrada e Silva e Martim Francisco Ribeiro de Andrada, segue-se uma completa mudan\u00e7a administrativa e na vida p\u00fablica do pa\u00eds<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-1850: Vega se tornou a primeira estrela (al\u00e9m do Sol) a ser fotografada<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-1934: No Brasil, \u00e9 realizada a elei\u00e7\u00e3o presidencial indireta. Get\u00falio Vargas \u00e9 eleito presidente do pa\u00eds com 173 votos pela Assembleia Constituinte, derrotando Borges de Medeiros com 59 votos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-1955: Inaugura\u00e7\u00e3o da Disneyl\u00e2ndia em Anaheim, Calif\u00f3rnia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-1994: A sele\u00e7\u00e3o brasileira conquista a Copa do Mundo FIFA em partida contra a It\u00e1lia decidida nos p\u00eanaltis (3&#215;2)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-2007: Queda do Airbus A320 da companhia a\u00e9rea TAM no Aeroporto de Congonhas (S\u00e3o Paulo), que fazia o voo 3054, com 187 pessoas a bordo. Este \u00e9 considerado o pior acidente a\u00e9reo da hist\u00f3ria brasileira, da Am\u00e9rica Latina, e o 11\u00b0 do mundo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Essas s\u00e3o algumas not\u00edcias do dia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Compartilhado por <a href=\"https:\/\/www.facebook.com\/litoral24h?__cft__[0]=AZWRn9FTg6V_sK3RlPOSaDd-nHWPTywyFSRr4XC1UYLnRZztc3zgjMDgh8CLdASU7VT7oRet8UTn7FbctTTe0JQmE_qpUY5WbnG3OMNi8mzOZ00VUnnXVjYdSLKAPwOzEadIxxYUYX6zmBcZTUtmUxhd3bCaoQHnUXERX8CsHjnWY5nZNc595hcZ2YDbebhowyhaCg0pidByxJnM8MU1WzdG&amp;__tn__=-]K-R\">Litoral 24h Online<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>NOT\u00cdCIAS DO DIA &#8211; ANO 8 n\u00b0 2797 Dia 17 de Julho de 2024, Quarta-Feira DATAS COMEMORATIVAS Dia de Prote\u00e7\u00e3o \u00e0s Florestas Dia do Curupira Dia do Submarinista Dia Mundial do Emoji TEMPERATURA E INDICADORES FINANCEIROS M\u00edn 22\u00b0 M\u00e1x 27\u00b0 (Aracaju-SE) D\u00f3lar Com: 0,3% R$ 5,42 Euro: 0,27% R$ 5,91 Ibovespa: 0,16% 129.110 pts Bitcoin: [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-141530","post","type-post","status-publish","format-standard","hentry","category-engracadas"],"_links":{"self":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts\/141530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/comments?post=141530"}],"version-history":[{"count":1,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts\/141530\/revisions"}],"predecessor-version":[{"id":141531,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts\/141530\/revisions\/141531"}],"wp:attachment":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/media?parent=141530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/categories?post=141530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/tags?post=141530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}