
{"id":160786,"date":"2025-09-25T08:44:07","date_gmt":"2025-09-25T11:44:07","guid":{"rendered":"https:\/\/www.largadoemguarapari.com.br\/13largado\/?p=160786"},"modified":"2025-09-25T08:44:07","modified_gmt":"2025-09-25T11:44:07","slug":"noticias-do-dia-764","status":"publish","type":"post","link":"https:\/\/www.largadoemguarapari.com.br\/13largado\/noticias-do-dia-764\/","title":{"rendered":"NOT\u00cdCIAS DO DIA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u2705 NOT\u00cdCIAS DO DIA &#8211; ANO 9 n\u00b0 3232<br \/>Dia 25 de Setembro de 2025, Quinta-Feira<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">DATAS COMEMORATIVAS<br \/>Dia da Radiodifus\u00e3o<br \/>Dia da Tia Solteirona<br \/>Dia do Auditor da Justi\u00e7a Desportiva<br \/>Dia Nacional do R\u00e1dio<br \/>Dia Nacional do Tr\u00e2nsito<br \/>Dia Internacional do Farmac\u00eautico<br \/>Dia Mar\u00edtimo Mundial<br \/>Dia Mundial do Pulm\u00e3o<br \/>Dia Mundial do Sonho<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">TEMPERATURA E INDICADORES FINANCEIROS<br \/>\u26c5 M\u00edn 22\u00b0 M\u00e1x 30\u00b0 (Salvador-BA)<br \/>\ud83d\udcb5 D\u00f3lar Com \u2b06\ufe0f 0,9% R$ 5,32<br \/>\ud83d\udcb6 Euro \u2b06\ufe0f 0,23% R$ 6,25<br \/>\ud83d\udcca Ibovespa \u2b06\ufe0f 0,05% 146.491 pts<br \/>\ud83e\ude99 Bitcoin \u2b06\ufe0f 2,25% R$ 605.211,05<br \/>\ud83d\udcb2IPCA \u2b07\ufe0f 0,11% Agosto de 2025<br \/>\ud83d\udcb2SELIC \u2b06\ufe0f 15% 18 de Setembro de 2025<br \/>\ud83d\udfe8 Ouro (grama) \u2b06\ufe0f R$ 645,37<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Colabore voluntariamente com o Informativo Di\u00e1rio &#8220;NOT\u00cdCIAS DO DIA &#8211; FISHING NEWS&#8221;<br \/>PIX (41) 99646-0100<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\udde7\ud83c\uddf7\ud83d\udcf0 NOT\u00cdCIAS NACIONAIS<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\udde7\ud83c\uddf7\ud83d\udc65 Comiss\u00e3o de Constitui\u00e7\u00e3o (CCJ) e Justi\u00e7a do Senado Federal rejeita PEC da Blindagem por unanimidade; presidente do colegiado, Otto Alencar, trabalhou ao lado do relator, Alessandro Vieira, para \u2018enterrar\u2019 a proposi\u00e7\u00e3o, que teve ampla rejei\u00e7\u00e3o da popula\u00e7\u00e3o; placar foi de 27 votos favor\u00e1veis<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\udde7\ud83c\uddf7\ud83d\udc65 Comiss\u00e3o do Senado aprova projeto que amplia isen\u00e7\u00e3o do Imposto de Renda; proposta isenta do IR pessoas com rendimentos mensais de at\u00e9 R$ 5 mil, a partir de 2026; h\u00e1 a expectativa de ser estabelecido tamb\u00e9m um desconto decrescente para aqueles que recebem entre R$ 5.001 e R$ 7.350<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\udde7\ud83c\uddf7\ud83d\udc65 Perito Eduardo Tagliaferro, ex-assessor de Alexandre de Moraes no Tribunal Superior Eleitoral (TSE), afirma que o ministro fez um \u201cmutir\u00e3o de persegui\u00e7\u00e3o \u00e0 direita\u201d quando presidiu a Corte, entre 2022 e 2024; em audi\u00eancia na C\u00e2mara nesta quarta-feira (24), ele relatou a deputados que perfis conservadores eram monitorados e derrubados em redes sociais por orienta\u00e7\u00e3o de servidores e integrantes de comiss\u00f5es internas do TSE<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2696\ufe0f Defesa de Bolsonaro pede ao STF revoga\u00e7\u00e3o da pris\u00e3o domiciliar e restri\u00e7\u00f5es ao uso de redes sociais; segundo os advogados, as limita\u00e7\u00f5es n\u00e3o seriam necess\u00e1rias, j\u00e1 que Bolsonaro n\u00e3o \u00e9 alvo direto da den\u00fancia apresentada pela Procuradoria-Geral da Rep\u00fablica (PGR) contra o deputado federal Eduardo Bolsonaro e o apresentador Paulo Figueiredo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2696\ufe0f Carla Zambelli nega ordem para invadir sistema do Conselho Nacional de Justi\u00e7a (CNJ) em depoimento virtual; presa na It\u00e1lia, deputada afirmou que s\u00f3 teve acesso ao mandado de pris\u00e3o do ministro Alexandre de Moraes inserido no sistema do CNJ ap\u00f3s o crime cometido pelo hacker Walter Delgatti<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\ude94 Pol\u00edcia Federal participa de nova fase da Opera\u00e7\u00e3o AIFA (A\u00e7\u00e3o Integrada de Fiscaliza\u00e7\u00e3o Ambiental) contra ocupa\u00e7\u00f5es irregulares em \u00e1rea de preserva\u00e7\u00e3o ambiental; a\u00e7\u00e3o integrada resultou na demoli\u00e7\u00e3o de constru\u00e7\u00e3o irregular em Paranagu\u00e1 (PR)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\ude94 Pol\u00edcia Federal deflagra segunda fase da Opera\u00e7\u00e3o Ultima Fumus, para desarticular organiza\u00e7\u00e3o criminosa em Mato Grosso do Sul; as investiga\u00e7\u00f5es tiveram in\u00edcio em janeiro de 2024, ap\u00f3s a apreens\u00e3o de uma carga de 1,5 tonelada de coca\u00edna, em Ara\u00e7atuba (SP)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udee9\ufe0f\ud83d\udc65 Avi\u00e3o de pequeno porte cai e deixa quatro mortos em Aquidauana, no Pantanal de Mato Grosso do Sul; segundo informa\u00e7\u00f5es preliminares, a aeronave modelo Cessna explodiu ap\u00f3s atingir o solo e os corpos foram carbonizados<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2615 Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria (Anvisa) determina a apreens\u00e3o de todos os lotes do caf\u00e9 torrado e mo\u00eddo extraforte e do caf\u00e9 tradicional da marca C\u00e2mara, de empresa desconhecida, al\u00e9m de proibir a comercializa\u00e7\u00e3o, a distribui\u00e7\u00e3o, a fabrica\u00e7\u00e3o, a propaganda e o uso do produto; em nota, a Anvisa informou que a medida foi tomada depois que uma portaria da Subsecretaria de Vigil\u00e2ncia e Aten\u00e7\u00e3o Prim\u00e1ria \u00e0 Sa\u00fade do estado do Rio de Janeiro confirmou a origem desconhecida do produto. As empresas indicadas como fabricantes na embalagem, segundo a ag\u00eancia, n\u00e3o est\u00e3o regulares<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\udfe6 Banco Nacional de Desenvolvimento Econ\u00f4mico e Social (BNDES) financia R$ 3,3 bilh\u00f5es para projetos estrat\u00e9gicos em Santa Catarina; ser\u00e3o R$ 401 milh\u00f5es destinados a investimentos do estado em melhoria de estradas de rodagem; R$ 2,5 bilh\u00f5es para a Starnav Servi\u00e7os Mar\u00edtimos adquirir embarca\u00e7\u00f5es a serem constru\u00eddas no estaleiro Detroit Brasil, de Itaja\u00ed; e R$ 356 milh\u00f5es para expans\u00e3o da Cooperativa Agroindustrial Alfa, que passar\u00e1 a produzir biodiesel em Chapec\u00f3, no oeste catarinense<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\ude9c Agroneg\u00f3cio: M\u00e1quinas agr\u00edcolas brasileiras ter\u00e3o acesso \u00e0 internet via sat\u00e9lite de Elon Musk; nos \u00faltimos meses, a divis\u00e3o da empresa de sistemas aeroespaciais SpaceX, do empres\u00e1rio Elon Musk, firmou parcerias com importantes montadoras para come\u00e7ar a oferecer a solu\u00e7\u00e3o, tendo o Brasil, um dos maiores produtores agr\u00edcolas do mundo, entre seus principais focos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udc65 N\u00famero de empresas industriais que usam Intelig\u00eancia Artificial (IA) cresce 163% em dois anos; no primeiro semestre do ano passado, 41,9% das empresas industriais pesquisadas faziam uso da IA, enquanto essa marca era de 16,9% dois anos antes; a constata\u00e7\u00e3o est\u00e1 na Pesquisa de Inova\u00e7\u00e3o Semestral (Pintec), divulgada nesta quarta-feira (24) pelo Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udcb0Sorteio de hoje da Mega-Sena 2919 pode pagar pr\u00eamio acumulado de R$ 54 milh\u00f5es<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CI\u00caNCIA e TECNOLOGIA<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\ude80 Nasa deve substituir Esta\u00e7\u00e3o Espacial Internacional por esta\u00e7\u00e3o comercial; ap\u00f3s 25 anos de opera\u00e7\u00e3o cont\u00ednua, a EEI ser\u00e1 desativada em 2030; empresas privadas competem para desenvolver sua substituta, com primeiro lan\u00e7amento previsto para 2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\ude80 Nave mais distante da Terra vai mapear bolha protetora do Sistema Solar; nova miss\u00e3o da Nasa foi lan\u00e7ada nesta quarta-feira (24) e foi pensada para investigar a heliosfera<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83e\udd88 Primeiro registro de acasalamento de tubar\u00f5es-leopardo revela sexo a tr\u00eas; bi\u00f3logo marinho documenta raro &#8220;tri\u00e2ngulo amoroso&#8221; entre tubar\u00f5es-leopardo amea\u00e7ados de extin\u00e7\u00e3o, contribuindo para esfor\u00e7os de conserva\u00e7\u00e3o da esp\u00e9cie<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ESPORTES<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u26bd Ta\u00e7a Libertadores<br \/>Quartas de Final, jogo 2:<br \/>Palmeiras (Bra) 3&#215;1 River Plate (Arg)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u26bd Copa Sul-Americana<br \/>Quartas de Final, jogo 2:<br \/>Atl\u00e9tico-MG (Bra) 1&#215;0 Bol\u00edvar (Bol)<br \/>Once Caldas (Col) (4)0x2(5) Independiente del Valle (Equ)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u26bd Campeonato Brasileiro<br \/>S\u00e9rie A, 16\u00aa rodada (jogos adiados):<br \/>Gr\u00eamio 1&#215;1 Botafogo<br \/>Vasco 3&#215;1 Bahia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00e9rie B, 28\u00aa rodada:<br \/>Athletic Club 0x3 Athletico-PR<br \/>CRB 3&#215;2 Botafogo-SP<br \/>Vila Nova-GO 2&#215;2 Cuiab\u00e1<br \/>Oper\u00e1rio-PR 2&#215;1 Amazonas<br \/>Volta Redonda 2&#215;1 Remo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u26bd\ud83d\udc64 Brasileir\u00e3o chega a 19 trocas de treinador e supera m\u00e9dia recorde de 2010; estat\u00edstica j\u00e1 \u00e9 superior \u00e0 edi\u00e7\u00e3o de 2024, quando 17 t\u00e9cnicos foram trocados at\u00e9 o final do ano; todas as equipes do atual G-4 (Flamengo, Cruzeiro, Palmeiras e Mirassol) mant\u00eam sua comiss\u00e3o t\u00e9cnica at\u00e9 o momento<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\udfca\ud83c\udffb\ud83e\udd47Gabrielzinho \u00e9 tricampe\u00e3o dos 200m livre e chega a oito ouros em Mundiais Paral\u00edmpicos de nata\u00e7\u00e3o; campe\u00e3o paral\u00edmpico mant\u00e9m 100% em sua classe em Mundiais, e Brasil quebra recorde mundial no revezamento 4x100m medley misto para pessoas com defici\u00eancias visuais<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\udf0d\ud83d\udcf0 NOT\u00cdCIAS INTERNACIONAIS<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddfa\ud83c\udde6\ud83c\uddf7\ud83c\uddfa Drones da Ucr\u00e2nia atacam principal petroqu\u00edmica da R\u00fassia; complexo que produz gasolina, diesel, querosene e outros derivados de petr\u00f3leo tem sido alvo de ofensivas ucranianas frequentes<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddfa\ud83c\udde6\ud83c\uddf7\ud83c\uddfa Na ONU, Zelensky diz que n\u00e3o h\u00e1 cessar-fogo por recusa da R\u00fassia; presidente ucraniano tamb\u00e9m afirmou que Moscou sequestrou milhares de crian\u00e7as na guerra<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddf7\ud83c\uddfa\ud83c\uddee\ud83c\uddf7 R\u00fassia assina acordo com Ir\u00e3 para constru\u00e7\u00e3o pequenas usinas nucleares em territ\u00f3rio iraniano; o diretor-geral da ag\u00eancia nuclear russa Rosatom, Alexey Likhachev, recebeu em Moscou o vice-presidente do Ir\u00e3 e presidente da Organiza\u00e7\u00e3o de Energia At\u00f4mica, Mohammad Eslami, ap\u00f3s o que procederam \u00e0 assinatura do documento bilateral<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\udde9\ud83c\uddf0 Drones fecham aeroporto na Dinamarca pela segunda vez em uma semana; o avistamento do drone ocorre dois dias ap\u00f3s a identifica\u00e7\u00e3o de dois ou tr\u00eas drones de grande porte terem interrompido todas as decolagens e pousos por quase quatro horas no aeroporto da capital Copenhague, no que a primeira-ministra chamou de \u201cgrave ataque \u00e0 infraestrutura cr\u00edtica dinamarquesa\u201d; segundo autoridades, n\u00e3o est\u00e1 claro se os casos est\u00e3o relacionados, mas o padr\u00e3o foi semelhante<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddee\ud83c\uddf9 It\u00e1lia mobiliza fragata da Marinha para auxiliar flotilha com ajuda para Gaza; grupo de ativistas que tenta \u2018romper o bloqueio israelense\u2019 afirmou ter sido atacado perto da costa da Gr\u00e9cia por \u2018m\u00faltiplos drones\u2019, que provocaram explos\u00f5es em algumas das embarca\u00e7\u00f5es<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddf5\ud83c\uddf9 Chega critica reconhecimento do Estado palestino por Portugal: \u201cMulheres s\u00e3o objetos e o terrorismo manda\u201d; o l\u00edder do partido de direita nacionalista Chega, Andr\u00e9 Ventura, criticou nesta quarta-feira (24) o governo do premi\u00ea de Portugal, o conservador Lu\u00eds Montenegro, por ter reconhecido o Estado palestino no in\u00edcio desta semana<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddec\ud83c\udde7 Torre de igreja de 700 anos \u00e9 erguida em Londres para constru\u00e7\u00e3o de pr\u00e9dio; estrutura foi a \u00faltima parte do pr\u00e9dio que restou ap\u00f3s inc\u00eandio na cidade em 1666<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddee\ud83c\uddf7 Ir\u00e3 diz \u00e0 Assembleia da ONU que nunca tentar\u00e1 construir bomba nuclear; pa\u00eds do Oriente M\u00e9dio enfrenta restabelecimento de san\u00e7\u00f5es internacionais<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddf9\ud83c\uddfc Lago transborda em Taiwan ap\u00f3s passagem de supertuf\u00e3o; fen\u00f4meno natural causou chuvas torrenciais na regi\u00e3o e deixou ao menos 17 mortos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddf9\ud83c\udded Cratera enorme se abre em frente a hospital no centro de Bangkok, capital da Tail\u00e2ndia; segundo a m\u00eddia local, dois postes de energia e um caminh\u00e3o de reboque da delegacia local ca\u00edram no buraco<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\udde8\ud83c\uddf3 Jornalista detida por denunciar surto de Covid na China pega mais quatro anos de pris\u00e3o; Zhang Zhan, de 42 anos, foi condenada na \u00faltima sexta-feira (19) pelo regime comunista da China, sob a acusa\u00e7\u00e3o de \u201cprovocar brigas e criar dist\u00farbios\u201d; a decis\u00e3o foi denunciada por organiza\u00e7\u00f5es internacionais de direitos humanos como mais um exemplo da persegui\u00e7\u00e3o do Partido Comunista contra vozes cr\u00edticas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddfa\ud83c\uddf8 Ataque a tiros deixa tr\u00eas feridos em um escrit\u00f3rio federal do ICE (Servi\u00e7o Imigra\u00e7\u00e3o e Alf\u00e2ndega dos Estados Unidos) em Dallas, no Texas, de acordo com o diretor interino do ICE, Todd Lyons; segundo autoridades, informa\u00e7\u00f5es preliminares apontam para um atirador<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddfa\ud83c\uddf8 EUA adiam taxa adicional para emiss\u00e3o do visto americano; o Congresso e o governo dos Estados Unidos negociaram o adiamento de uma nova taxa de US$ 250 (cerca de R$ 1.330) para emiss\u00e3o do visto americano, que deveria entrar em vigor no dia 1\u00ba de outubro<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddec\ud83c\uddfe Guiana apela \u00e0 ONU por amea\u00e7a de anexa\u00e7\u00e3o da Venezuela; Irfaan Ali, presidente do pa\u00eds, acusou Caracas de promulgar leis unilaterais e amea\u00e7ar seu territ\u00f3rio, apesar das medidas provis\u00f3rias do Tribunal Internacional de Justi\u00e7a<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddfb\ud83c\uddea\ud83d\udee9\ufe0f Avi\u00e3o de pequeno porte cai pr\u00f3ximo ao Aeroporto Internacional Sim\u00f3n Bol\u00edvar, no estado de La Guaira, na Venezuela, e deixa duas pessoas feridas; segundo o Instituto Nacional de Aeron\u00e1utica Civil do pa\u00eds, as v\u00edtimas receberam cuidados m\u00e9dicos e est\u00e3o em &#8220;condi\u00e7\u00f5es est\u00e1veis&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddfb\ud83c\uddea Terremoto de magnitude 6,2 atinge norte da Venezuela; o abalo s\u00edsmico ocorreu a uma profundidade de 10 km, segundo o Centro Alem\u00e3o de Pesquisa em Geoci\u00eancias (GFZ)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\udf0d EVENTOS HIST\u00d3RICOS DO DIA<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-275: Pela \u00faltima vez, o Senado Romano escolhe um imperador (Marco Cl\u00e1udio T\u00e1cito)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-1237: Inglaterra e Esc\u00f3cia assinam o Tratado de Iorque, estabelecendo a localiza\u00e7\u00e3o de sua fronteira comum<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-1935: Assis Chateaubriand, um jornalista, escritor e empres\u00e1rio brasileiro, inaugura a PRG-3, Super R\u00e1dio Tupi do Rio de Janeiro<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-1977: Cerca de 4.200 pessoas participam da primeira corrida da Maratona de Chicago<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-1978: O voo Pacific Southwest Airlines 182, um Boeing 727, colide no ar com um Cessna 172 e cai em San Diego, na Calif\u00f3rnia (EUA), matando 144 pessoas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-1981: Belize \u00e9 admitido como Estado-membro da ONU<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-1992: A NASA lan\u00e7a o Mars Observer; onze meses depois, a sonda falharia ao se preparar para a inser\u00e7\u00e3o orbital<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-1998: Reinaugura\u00e7\u00e3o do Museu do Caf\u00e9 do Brasil, na cidade de Santos (SP)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-2020: A It\u00e1lia vota para emendar sua constitui\u00e7\u00e3o para reduzir o tamanho de seu Parlamento em um ter\u00e7o<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Essas s\u00e3o algumas not\u00edcias do dia \u2705<br \/>Autor: Roberto Vieira Filho \ud83c\udde7\ud83c\uddf7\ud83c\udf0e<br \/>Bom Dia!!! \ud83d\udc4d\ud83c\udffc\ud83d\ude09<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2705 NOT\u00cdCIAS DO DIA &#8211; ANO 9 n\u00b0 3232Dia 25 de Setembro de 2025, Quinta-Feira DATAS COMEMORATIVASDia da Radiodifus\u00e3oDia da Tia SolteironaDia do Auditor da Justi\u00e7a DesportivaDia Nacional do R\u00e1dioDia Nacional do Tr\u00e2nsitoDia Internacional do Farmac\u00eauticoDia Mar\u00edtimo MundialDia Mundial do Pulm\u00e3oDia Mundial do Sonho TEMPERATURA E INDICADORES FINANCEIROS\u26c5 M\u00edn 22\u00b0 M\u00e1x 30\u00b0 (Salvador-BA)\ud83d\udcb5 D\u00f3lar Com [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-160786","post","type-post","status-publish","format-standard","hentry","category-engracadas"],"_links":{"self":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts\/160786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/comments?post=160786"}],"version-history":[{"count":1,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts\/160786\/revisions"}],"predecessor-version":[{"id":160787,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts\/160786\/revisions\/160787"}],"wp:attachment":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/media?parent=160786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/categories?post=160786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/tags?post=160786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}