
{"id":171971,"date":"2026-06-26T08:02:06","date_gmt":"2026-06-26T11:02:06","guid":{"rendered":"https:\/\/www.largadoemguarapari.com.br\/13largado\/?p=171971"},"modified":"2026-06-26T08:02:06","modified_gmt":"2026-06-26T11:02:06","slug":"noticias-do-dia-991","status":"publish","type":"post","link":"https:\/\/www.largadoemguarapari.com.br\/13largado\/noticias-do-dia-991\/","title":{"rendered":"NOT\u00cdCIAS DO DIA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u2705 NOT\u00cdCIAS DO DIA &#8211; ANO 10 n\u00b0 3506<br \/>Dia 26 de Junho de 2026, Sexta-Feira<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">DATAS COMEMORATIVAS<br \/>Dia da Avia\u00e7\u00e3o de Busca e Salvamento<br \/>Dia do Metrologista<br \/>Dia Nacional do Diabetes<br \/>Dia Internacional contra o Abuso e Tr\u00e1fico Il\u00edcito de Drogas<br \/>Dia Internacional de Apoio \u00e0s V\u00edtimas de Tortura<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">TEMPERATURA E INDICADORES FINANCEIROS<br \/>\u26c5 M\u00edn 18\u2070 M\u00e1x 23\u2070 (Rio de Janeiro-RJ)<br \/>\ud83d\udcb5 D\u00f3lar Com \u2b07\ufe0f 0,47% R$ 5,17<br \/>\ud83d\udcb6 Euro \u2b07\ufe0f 0,29% R$ 5,88<br \/>\ud83d\udcca Ibovespa \u2b06\ufe0f 087% 171.990 pts<br \/>\ud83e\ude99 Bitcoin \u2b07\ufe0f 1,73% R$ 312.266,21<br \/>\ud83d\udcb2IGP-M \u2b06\ufe0f 0,84% Maio de 2026<br \/>\ud83d\udcb2INPC \u2b06\ufe0f 0,65% Maio de 2026<br \/>\ud83d\udcb2IPCA \u2b06\ufe0f 0,58% Maio de 2026<br \/>\ud83d\udcb2SELIC \u2b06\ufe0f 14,25% 17 de Junho de 2026<br \/>\ud83d\udcb2TR \u2b06\ufe0f 0,17% 25 de Junho de 2026<br \/>\ud83d\udfe8 Ouro (grama) \u2b06\ufe0f R$ 672,99<br \/>Colabore voluntariamente com o Informativo Di\u00e1rio &#8220;NOT\u00cdCIAS DO DIA &#8211; FISHING NEWS&#8221;<br \/>PIX (41) 99646-0100<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\udde7\ud83c\uddf7\ud83d\udcf0 NOT\u00cdCIAS NACIONAIS<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\udde7\ud83c\uddf7\ud83c\uddfb\ud83c\uddea Brasil coloca equipes de sa\u00fade e insumos \u00e0 disposi\u00e7\u00e3o da Venezuela; o pa\u00eds vizinho foi afetado por fortes terremotos de 7.2 e 7.5 na escala ritcher na quarta-feira (24)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\udde7\ud83c\uddf7 Governo Federal cria Banco Nacional de Celulares com Restri\u00e7\u00e3o para fortalecer combate ao roubo, furto e recepta\u00e7\u00e3o de aparelhos; decreto institui base nacional integrada ao Sinesp para apoiar investiga\u00e7\u00f5es, facilitar a recupera\u00e7\u00e3o de celulares e ampliar a coopera\u00e7\u00e3o entre os \u00f3rg\u00e3os de seguran\u00e7a p\u00fablica<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\udde7\ud83c\uddf7\ud83d\udc65 Governo prepara pol\u00edtica nacional de embarque biom\u00e9trico para aeroportos; nova diretriz deve classificar coleta de dados biom\u00e9tricos como tema de seguran\u00e7a nacional e abrir caminho para expans\u00e3o da tecnologia nos terminais brasileiros<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\udde7\ud83c\uddf7\ud83d\udc64Teresa Leit\u00e3o \u00e9 a nova l\u00edder do governo no Senado; ela assume no lugar de Jaques Wagner que deixou a posi\u00e7\u00e3o nesta quarta-feira (24) ap\u00f3s ser alvo de opera\u00e7\u00e3o da Pol\u00edcia Federal, na semana passada, por suspeitas de corrup\u00e7\u00e3o no caso do Banco Master; os agentes acusam o senador de ter recebido vantagens do banqueiro Augusto Ferreira Lima, ex-s\u00f3cio do Master<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2696\ufe0f Fachin escolhe Mendon\u00e7a para relatoria do caso \u2018Dark Horse\u2019; na \u00faltima sexta-feira (19), a Procuradoria Geral da Rep\u00fablica j\u00e1 havia se posicionado a favor da redistribui\u00e7\u00e3o da not\u00edcia-crime do caso ao ministro<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2696\ufe0f Andr\u00e9 Mendon\u00e7a determina transfer\u00eancia de Vorcaro para \u2018Papudinha\u2019; o ministro do STF negou o pedido da defesa do banqueiro de convers\u00e3o da pris\u00e3o preventiva em cust\u00f3dia domiciliar<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2696\ufe0f\ud83d\ude94 Ministro Andr\u00e9 Mendon\u00e7a, do STF, cobra explica\u00e7\u00f5es sobre abordagem ao \u201cCareca do INSS\u201d na Papuda; defesa de Ant\u00f4nio Carlos Camilo Antunes afirma que policiais penais o questionaram, sem advogados, sobre poss\u00edvel dela\u00e7\u00e3o<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2696\ufe0f Caso Master: Procuradoria-Geral da Rep\u00fablica (PGR) rejeita proposta de dela\u00e7\u00e3o premiada de ex-presidente do Banco de Bras\u00edlia (BRB); procurador-geral Paulo Gonet afirmou que as informa\u00e7\u00f5es apresentadas por Paulo Henrique Costa n\u00e3o gerariam resultado diferente do alcan\u00e7ado pelos investigadores<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2696\ufe0f O procurador-geral da Rep\u00fablica, Paulo Gonet, diz que n\u00e3o v\u00ea falta grave no caso da arma de Bolsonaro; parecer foi solicitado pelo ministro Alexandre de Moraes<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\ude94\ud83d\udc65 Pol\u00edcia Federal v\u00ea liga\u00e7\u00e3o entre sacola em avi\u00e3o e repasse R$ 350 mil de Vorcaro a Ciro Nogueira; investiga\u00e7\u00e3o cruza relato de piloto, mensagens atribu\u00eddas a Daniel Vorcaro e registros de voo para apurar suposto repasse ao senador do PP<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\ude94 Pol\u00edcia Federal deflagrou, nesta quinta-feira (25\/6), em conjunto com o Minist\u00e9rio P\u00fablico Federal, a segunda fase da Opera\u00e7\u00e3o Disclosure, que busca aprofundar as investiga\u00e7\u00f5es sobre supostas fraudes cont\u00e1beis estimadas em, aproximadamente, R$ 54 bilh\u00f5es; na a\u00e7\u00e3o, policiais federais cumpriram nove mandados de busca e apreens\u00e3o, incluindo buscas pessoais, nas cidades do Rio de Janeiro (RJ) e de S\u00e3o Paulo (SP)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\ude94 Pol\u00edcia Federal apura fraudes em licita\u00e7\u00f5es e desvio de recursos p\u00fablicos em Guarajar\u00e1 (AM); a\u00e7\u00e3o investiga o direcionamento de licita\u00e7\u00f5es para favorecimento de empresas e pessoas f\u00edsicas determinadas, o qual resultou em preju\u00edzo ao er\u00e1rio municipal em, aproximadamente, R$ 190 mil<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\ude94\ud83d\udc65 \u2018Saidinha\u2019: centenas de presos n\u00e3o retornaram para a cadeia neste m\u00eas em SP; Secret\u00e1ria da Administra\u00e7\u00e3o Penitenci\u00e1ria de S\u00e3o Paulo informou que 718 presos de 28.498 que sa\u00edram do c\u00e1rcere em sa\u00edda tempor\u00e1ria n\u00e3o retornaram \u00e0s suas celas no estado; o per\u00edodo da amostra foi de 16\/06\/2026 a 23\/06\/2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udcbb\ud83d\udcf2 Receita Federal leiloa smartphones e notebooks em novo preg\u00e3o eletr\u00f4nico em S\u00e3o Paulo; \u00f3rg\u00e3o realizar\u00e1 um novo leil\u00e3o eletr\u00f4nico regional de mercadorias apreendidas para esvaziar dep\u00f3sitos e arrecadar recursos; com isso, ser\u00e3o disponibilizados lotes que incluem desde celulares de \u00faltima gera\u00e7\u00e3o at\u00e9 ve\u00edculos; os interessados ter\u00e3o at\u00e9 o dia 29 de junho para registrar suas propostas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2708\ufe0f GOL cancela voos de e para Caracas ap\u00f3s terremotos na Venezuela; viagens at\u00e9 o dia 5 de julho foram canceladas; tremores causaram destrui\u00e7\u00e3o no aeroporto da cidade<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udc68\ud83c\udffb\u200d\ud83d\ude92 Im\u00f3vel desaba e mata duas meninas na Ilha do Governador, na zona norte do Rio; duas meninas, de 11 anos e 4 anos, morreram sob os escombros; duas pessoas foram resgatadas com vida e sem ferimentos; equipes do Corpo de Bombeiros da Ilha do Governador, do Grupo de Opera\u00e7\u00f5es Especiais (Goesp) e do Grupamento de Busca e Resgate com C\u00e3es atuaram nos trabalhos de resgate das v\u00edtimas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\udfdb\ufe0f Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria (Anvisa) e Receita Federal deflagram a\u00e7\u00e3o contra o com\u00e9rcio de cigarros eletr\u00f4nicos; Opera\u00e7\u00e3o Rede de Fuma\u00e7a apreendeu mais de 25 mil dispositivos, que s\u00e3o produtos ilegais no Brasil<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\udfdb\ufe0f Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria (Anvisa) pro\u00edbe suplemento irregular e suspende lotes de creatina; ag\u00eancia determinou a apreens\u00e3o do suplemento alimentar em c\u00e1psulas da marca Artro100, produzido por empresa desconhecida; a resolu\u00e7\u00e3o, publicada nesta quinta-feira (25) no Di\u00e1rio Oficial da Uni\u00e3o, tamb\u00e9m pro\u00edbe a venda, a distribui\u00e7\u00e3o, a fabrica\u00e7\u00e3o, a divulga\u00e7\u00e3o e o uso do produto<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udc65\ud83d\udcf2 Ag\u00eancia Nacional de Telecomunica\u00e7\u00f5es (Anatel) concede anu\u00eancia para mudan\u00e7a de controle indireto na TIM; o Conselho Diretor da Anatel concedeu anu\u00eancia pr\u00e9via para uma altera\u00e7\u00e3o de controle indireto da TIM no Brasil, refletindo mudan\u00e7as acion\u00e1rias na matriz da empresa na It\u00e1lia; em mar\u00e7o, a estatal italiana de servi\u00e7os postais Poste Italiane anunciou uma opera\u00e7\u00e3o para adquirir 100% do Grupo TIM, controlador da tele brasileira; a Poste (que j\u00e1 era acionista da operadora europeia) espera concluir a tomada integral do controle neste ano<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udca1Ag\u00eancia Nacional de Energia El\u00e9trica (Aneel) aprova reajuste m\u00e9dio de 1,1% na conta de luz; novo valor passa a valer a partir do dia 1\u00ba de julho; o c\u00e1lculo \u00e9 feito com base nas Receitas Anuais Permitidas (RAP) das transmissoras e nas Tarifas de Uso do Sistema de Transmiss\u00e3o (TUST)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udd4c\ud83d\udc65 Romaria a Aparecida marca centen\u00e1rio das Irm\u00e3s de Maria; cerca de 70 religiosas participar\u00e3o da peregrina\u00e7\u00e3o; grupo de 21 Irm\u00e3s far\u00e1 caminhada de tr\u00eas dias at\u00e9 a Casa da M\u00e3e Aparecida; o Instituto Secular das Irm\u00e3s de Maria de Schoenstatt realizar\u00e1, no pr\u00f3ximo dia 6 de julho de 2026, uma romaria especial ao Santu\u00e1rio Nacional de Aparecida, em Aparecida (SP); a peregrina\u00e7\u00e3o integra as comemora\u00e7\u00f5es pelos 100 anos de funda\u00e7\u00e3o do Instituto e reunir\u00e1 cerca de 70 religiosas das duas prov\u00edncias brasileiras da comunidade: Santa Maria (RS) e Atibaia (SP)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CI\u00caNCIA e TECNOLOGIA<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddea\ud83c\uddfa\ud83c\udde7\ud83c\uddf7 Uni\u00e3o Europeia defende soberania digital e amplia coopera\u00e7\u00e3o tecnol\u00f3gica com o Brasil; comiss\u00e1rio europeu Jozef S\u00edkela destaca parceria em intelig\u00eancia artificial, conectividade e governan\u00e7a digital durante f\u00f3rum realizado no Rio de Janeiro<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udc65 IBM anuncia primeiro chip com arquitetura abaixo de 1 nan\u00f4metro; empresa anuncia chip de 0,7 nm com arquitetura in\u00e9dita, prometendo mais desempenho, efici\u00eancia energ\u00e9tica e avan\u00e7o na computa\u00e7\u00e3o<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udcf2 TIM libera transfer\u00eancia de eSIM entre Android e iPhone; operadora se torna a primeira da Am\u00e9rica do Sul com nova solu\u00e7\u00e3o tecnol\u00f3gica para eSIM<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddeb\ud83c\uddf7 Escava\u00e7\u00e3o revela sete mil anos de ocupa\u00e7\u00e3o humana no vale do Meuse, na Fran\u00e7a; pesquisa realizada em Ancemont identificou vest\u00edgios que v\u00e3o do Neol\u00edtico \u00e0 Primeira Guerra Mundial e mostra ocupa\u00e7\u00e3o cont\u00ednua da regi\u00e3o ao longo de mil\u00eanios<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udc65 Amazon anuncia mais US$ 13 bilh\u00f5es na \u00cdndia para refor\u00e7ar infraestrutura de Intelig\u00eancia Artificial (IA); a empresa tamb\u00e9m afirmou que pretende inaugurar mais de 20 centros de distribui\u00e7\u00e3o e mais de 100 esta\u00e7\u00f5es de entrega em toda a \u00cdndia ainda neste ano<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ESPORTES<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u26bd Copa do Mundo Fifa 2026<br \/>Fase de Grupos, 3\u00aa rodada:<br \/>Cura\u00e7ao 0x2 Costa do Marfim<br \/>Equador 2&#215;1 Alemanha<br \/>Jap\u00e3o 1&#215;1 Su\u00e9cia<br \/>Tun\u00edsia 1&#215;3 Holanda<br \/>Paraguai 0x0 Austr\u00e1lia<br \/>Turquia 3&#215;2 Estados Unidos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u26bd Campeonato Brasileiro<br \/>S\u00e9rie B, 15\u00aa rodada:<br \/>Cuiab\u00e1 2&#215;2 Londrina<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u26bd Brasil enfrentar\u00e1 o Jap\u00e3o na segunda fase da Copa do Mundo; sele\u00e7\u00f5es j\u00e1 se enfrentaram quatro vezes em edi\u00e7\u00f5es anteriores da competi\u00e7\u00e3o; canarinha leva vantagem contra o advers\u00e1rio; jogo vai acontecer na segunda-feira (29), \u00e0s 14h<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u26bd\ud83c\udff3\ufe0f\u200d\ud83c\udf08 Fifa permite bandeiras LGBT em Seattle e ignora pedido de veto de Ir\u00e3 e Egito; Comit\u00ea Organizador Local estabelece marca de &#8220;Jogo do Orgulho&#8221; na semana da Parada de Seattle justamente entre sele\u00e7\u00f5es de pa\u00edses que criminalizam pessoas LGBTQIAPN+<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\udfc0\ud83d\udc64Lakers decidem renovar com Austin Reaves por quatro anos e mais de R$ 190 milh\u00f5es, diz portal; de acordo com a imprensa internacional, astro assinar\u00e1 o contrato mais caro da hist\u00f3ria da NBA para um jogador n\u00e3o draftado<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\udfce\ufe0f Federa\u00e7\u00e3o Internacional do Automobilismo (FIA) aprova mandatos ilimitados e abre caminho para perman\u00eancia de Ben Sulayem; o presidente da entidade, Mohammed Ben Sulayem havia proposto o fim do limite de mandatos na federa\u00e7\u00e3o; antes, gestores n\u00e3o podiam passar mais que 12 anos no cargo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\udf0d\ud83d\udcf0 NOT\u00cdCIAS INTERNACIONAIS<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddee\ud83c\uddf9 Pol\u00edcia acha esconderijo de haxixe em caverna de ilha tur\u00edstica na It\u00e1lia; autoridades da ilha de Ponza apreenderam 330 blocos da droga, pesando 40 quilogramas no total, em caverna acess\u00edvel apenas pelo mar<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddeb\ud83c\uddf7\u2600\ufe0f Onda de calor: Prefeito de Paris alerta para aumento de mortes; Emmanuel Gregoire aponta crescimento de chamadas de emerg\u00eancia e interna\u00e7\u00f5es hospitalares na capital francesa em meio a recordes de temperatura<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddee\ud83c\uddf1\ud83c\uddf1\ud83c\udde7 Ex\u00e9rcito de Israel anuncia redu\u00e7\u00e3o &#8220;tempor\u00e1ria&#8221; de for\u00e7as no L\u00edbano; For\u00e7as de Defesa de Israel (FDI) afirmaram que retirar\u00e3o &#8220;v\u00e1rias brigadas&#8221; tanto do setor norte quanto do sul \u2013 referindo-se ao territ\u00f3rio liban\u00eas e a Gaza<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddf9\ud83c\uddfc Tuf\u00e3o for\u00e7a retirada de dois milh\u00f5es de japoneses e paralisa partes de Taiwan; deslocamentos em massa, interrup\u00e7\u00e3o de transportes e alertas de desastres mobilizam autoridades em meio a fortes impactos de tempestades na regi\u00e3o<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddfa\ud83c\uddf8\ud83d\udd25Inc\u00eandio em pr\u00e9dio comercial na cidade americana de Allentown, no estado da Pensilv\u00e2nia, nos EUA, obriga moradores a fugirem de casa; imagens a\u00e9reas mostram equipes atuando para controlar o fogo, enquanto popula\u00e7\u00e3o foi orientada a deixar regi\u00e3o<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddfb\ud83c\uddea Terremotos na Venezuela: n\u00famero de mortos sobe para 235; h\u00e1 mais de 1.500 feridos, 200 pessoas presas sob escombros e 157 desaparecidos, segundo presidente da Assembleia Nacional do pa\u00eds<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddfb\ud83c\uddea\ud83d\udc65 Venezuelanos afetados por terremotos enfrentam segunda noite nas ruas; equipes de resgate seguem as buscas por desaparecidos, enquanto milhares permanecem fora de casa<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddfb\ud83c\uddea Terremoto foi o maior da Venezuela em mais de um s\u00e9culo, mostram registros; Servi\u00e7o Geol\u00f3gico dos Estados Unidos (USGS) indica que tremor de magnitude 7,5, desta quarta-feira (24), foi o mais forte no pa\u00eds desde o evento de 1900 de magnitude 7,7<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddfb\ud83c\uddea Venezuela registrou 138 r\u00e9plicas de tremores ap\u00f3s dois terremotos mortais; informa\u00e7\u00e3o foi divulgada pelo presidente da Assembleia Nacional do pa\u00eds, Jorge Rodr\u00edguez<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddfb\ud83c\uddea Terremotos na Venezuela: M\u00e9xico e EUA enviam equipes de elite para buscas; autoridades venezuelanas ainda buscam por desaparecidos ap\u00f3s pr\u00e9dios desabarem no pa\u00eds<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddfb\ud83c\uddea Autoridades da Venezuela pedem doa\u00e7\u00f5es de \u00e1gua e m\u00e1scaras ap\u00f3s terremotos; escolas e outros pr\u00e9dios p\u00fablicos foram transformados em pontos de coleta de suprimentos de emerg\u00eancia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddfa\ud83c\uddf3\ud83c\uddfb\ud83c\uddea Secret\u00e1rio-geral da ONU, Ant\u00f3nio Guterres, lamenta terremotos mortais na Venezuela e mobiliza ajuda; centro de coordena\u00e7\u00e3o foi estabelecido em Caracas para ajudar a direcionar o aux\u00edlio aos mais necessitados<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddfb\ud83c\udde6\ud83c\uddfb\ud83c\uddea Papa Le\u00e3o XIV envia doa\u00e7\u00e3o de 100 mil euros \u00e0 Venezuela ap\u00f3s terremotos; tremores j\u00e1 deixaram ao menos 188 mortos e mais de 1.500 feridos, segundo o presidente da Assembleia Nacional, Jorge Rodr\u00edguez<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\udf0d EVENTOS HIST\u00d3RICOS DO DIA<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-684: \u00c9 eleito o Papa Bento II<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-1483: Ricardo III torna-se rei da Inglaterra<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-1862: Imp\u00e9rio do Brasil: o Sistema M\u00e9trico Franc\u00eas \u00e9 adotado no pa\u00eds<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-1886: Henri Moissan, um qu\u00edmico franc\u00eas, isola o elemento fl\u00faor pela primeira vez<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-1924: A ocupa\u00e7\u00e3o norte-americana na Rep\u00fablica Dominicana termina ap\u00f3s oito anos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-1936: Voo inaugural do Focke-Wulf Fw 61, o primeiro helic\u00f3ptero completamente control\u00e1vel<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-1968: Ocorre a Passeata dos Cem Mil, uma manifesta\u00e7\u00e3o popular de protesto contra o Governo Militar no Brasil<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-1976: A Torre CN, na \u00e9poca, a maior estrutura autossustentada do mundo, \u00e9 Inaugurada em Toronto, Canad\u00e1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-1978: O voo 189 da Air Canada, um McDonnell Douglas DC-9, voando para Toronto, ultrapassa a pista e cai na ravina de Etobicoke Creek. Dois dos 107 passageiros a bordo morrem<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-1988: A primeira queda de um Airbus A320 ocorre quando o voo 296Q da Air France cai no aer\u00f3dromo Mulhouse-Habsheim em Habsheim, Fran\u00e7a, durante um show a\u00e9reo, matando tr\u00eas das 136 pessoas a bordo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-2000: Papa Jo\u00e3o Paulo II revela o terceiro segredo de F\u00e1tima<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-2006: Mari Alkatiri, o primeiro Primeiro-Ministro de Timor Leste, demite-se ap\u00f3s semanas de agita\u00e7\u00e3o pol\u00edtica<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-2007: O Papa Bento XVI restabelece as leis tradicionais da elei\u00e7\u00e3o papal em que um candidato bem-sucedido deve receber dois ter\u00e7os dos votos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-2015: Cinco diferentes ataques terroristas na Fran\u00e7a, Tun\u00edsia, Som\u00e1lia, Kuwait e S\u00edria ocorreram no que foi apelidado de Sexta-Feira Sangrenta pela m\u00eddia internacional. Mais de 750 pessoas foram mortas ou feridas nesses ataques.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Essas s\u00e3o algumas not\u00edcias do dia \u2705<br \/>Autor: Roberto Vieira Filho \ud83c\udde7\ud83c\uddf7\ud83c\udf0e<br \/>Bom Dia!!! \ud83d\udc4d\ud83c\udffc\ud83d\ude09<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2705 NOT\u00cdCIAS DO DIA &#8211; ANO 10 n\u00b0 3506Dia 26 de Junho de 2026, Sexta-Feira DATAS COMEMORATIVASDia da Avia\u00e7\u00e3o de Busca e SalvamentoDia do MetrologistaDia Nacional do DiabetesDia Internacional contra o Abuso e Tr\u00e1fico Il\u00edcito de DrogasDia Internacional de Apoio \u00e0s V\u00edtimas de Tortura TEMPERATURA E INDICADORES FINANCEIROS\u26c5 M\u00edn 18\u2070 M\u00e1x 23\u2070 (Rio de Janeiro-RJ)\ud83d\udcb5 [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-171971","post","type-post","status-publish","format-standard","hentry","category-engracadas"],"_links":{"self":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts\/171971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/comments?post=171971"}],"version-history":[{"count":1,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts\/171971\/revisions"}],"predecessor-version":[{"id":171972,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts\/171971\/revisions\/171972"}],"wp:attachment":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/media?parent=171971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/categories?post=171971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/tags?post=171971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}