
{"id":172401,"date":"2026-07-13T07:36:13","date_gmt":"2026-07-13T10:36:13","guid":{"rendered":"https:\/\/www.largadoemguarapari.com.br\/13largado\/?p=172401"},"modified":"2026-07-13T07:36:13","modified_gmt":"2026-07-13T10:36:13","slug":"noticias-do-dia-1007","status":"publish","type":"post","link":"https:\/\/www.largadoemguarapari.com.br\/13largado\/noticias-do-dia-1007\/","title":{"rendered":"NOT\u00cdCIAS DO DIA"},"content":{"rendered":"\n<p>\u2705 NOT\u00cdCIAS DO DIA &#8211; ANO 10 n\u00b0 3523<br \/>Dia 13 de Julho de 2026, Segunda-Feira<\/p>\n\n\n\n<p>DATAS COMEMORATIVAS<br \/>Dia do Cantor<br \/>Dia dos Compositores e Cantores Sertanejos<br \/>Dia do Engenheiro de Saneamento<br \/>Dia Mundial de Conscientiza\u00e7\u00e3o sobre o TDAH<br \/>Dia Mundial do Rock<\/p>\n\n\n\n<p>TEMPERATURA E INDICADORES FINANCEIROS<br \/>\u26c5 M\u00edn 24\u2070 M\u00e1x 31\u2070 (Bel\u00e9m-PA)<br \/>\ud83d\udcb5 D\u00f3lar Com \u2b07\ufe0f 0,28% R$ 5,10<br \/>\ud83d\udcb6 Euro \u2b07\ufe0f 0,38% R$ 5,83<br \/>\ud83d\udcca Ibovespa \u2b06\ufe0f 2,97% 177.866 pts<br \/>\ud83e\ude99 Bitcoin \u2b07\ufe0f 0,2% R$ 325.951,35<br \/>\ud83d\udcb2IGP-M \u2b07\ufe0f 0,5% Junho de 2026<br \/>\ud83d\udcb2INPC \u2b06\ufe0f 0,14% Junho de 2026<br \/>\ud83d\udcb2IPCA \u2b06\ufe0f 0,16% Junho de 2026<br \/>\ud83d\udcb2SELIC \u2b06\ufe0f 14,25% 17 de Junho de 2026<br \/>\ud83d\udcb2TR \u2b06\ufe0f 0,17% 10 de Julho de 2026<br \/>\ud83d\udfe8 Ouro (grama) \u2b07\ufe0f R$ 669,90<br \/>Colabore voluntariamente com o Informativo Di\u00e1rio &#8220;NOT\u00cdCIAS DO DIA &#8211; FISHING NEWS&#8221;<br \/>PIX (41) 99646-0100<\/p>\n\n\n\n<p>\ud83c\udde7\ud83c\uddf7\ud83d\udcf0 NOT\u00cdCIAS NACIONAIS<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>\ud83c\udde7\ud83c\uddf7\ud83d\udc65 Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE) iniciou, na \u00faltima semana, a coleta da terceira edi\u00e7\u00e3o da Pesquisa Nacional de Sa\u00fade (PNS 2026), realizada em parceria com o Minist\u00e9rio da Sa\u00fade; a PNS \u00e9 realizada por amostragem; at\u00e9 30 de novembro, cerca de 1,8 mil entrevistadores visitar\u00e3o aproximadamente 140 mil domic\u00edlios distribu\u00eddos em todos os estados brasileiros<\/p>\n\n\n\n<p>\u2696\ufe0f\ud83d\udc64Moraes converte pris\u00e3o preventiva de pastor M\u00e1rcio Poncio em domiciliar com tornozeleira; a decis\u00e3o do ministro vem depois do pedido da defesa para que Poncio passasse a cumprir a pris\u00e3o em casa por causa da gravidez de alto risco da sua esposa, um mulher de 50 anos; Poncio foi preso no dia 3 de julho na quinta fase da Opera\u00e7\u00e3o Unha e Carne, que investiga um esquema de vazamento de informa\u00e7\u00f5es sigilosas em favor do Comando Vermelho; magnata da ind\u00fastria do tabaco, ele \u00e9 conhecido como \u201cpastor do cigarro\u201d<\/p>\n\n\n\n<p>\u2696\ufe0f\ud83d\ude94 Caso Master: Pol\u00edcia Federal v\u00ea troca de celular e fim da empresa em risco de fuga de Thiago Miranda; passagem comprada para os EUA para esta segunda-feira (13) tamb\u00e9m levou o STF a determinar apreens\u00e3o do passaporte de Miranda, publicit\u00e1rio ligado a Daniel Vorcaro; defesa nega<\/p>\n\n\n\n<p>\ud83c\udde7\ud83c\uddf7\ud83c\udde7\ud83c\uddf4\ud83d\ude94 Bol\u00edvia prende brasileiro suspeito de roubo de R$ 14 milh\u00f5es orquestrado pelo PCC; a pol\u00edcia boliviana prendeu um suspeito de participar do roubo milion\u00e1rio em uma aeronave pagadora no Aeroporto de Caxias do Sul, na Serra Ga\u00facha, em junho de 2024; a Pol\u00edcia Federal confirmou a pris\u00e3o, realizada em uma a\u00e7\u00e3o de coopera\u00e7\u00e3o policial internacional<\/p>\n\n\n\n<p>\ud83d\ude94 Pol\u00edcia Federal suspeita que Presid\u00eancia da C\u00e2mara deu aval para desvios de emendas; ministro Fl\u00e1vio Dino determinou bloqueio de R$ 6,1 milh\u00f5es do ex-deputado Eduardo Cunha; pol\u00edtico nega irregularidade em emendas e diz que questionar\u00e1 bloqueio de bens<\/p>\n\n\n\n<p>\ud83d\ude9a\ud83d\udc65 Caminhoneiros amea\u00e7am nova greve nacional por Medida Provis\u00f3ria (MP) do frete; categoria dos caminhoneiros pressiona Senado para vota\u00e7\u00e3o da MP do Piso do Frete at\u00e9 16 de julho, com risco de greve nacional<\/p>\n\n\n\n<p>\ud83d\udc65 Canetas emagrecedoras ampliam incertezas para redes de farm\u00e1cia; mudan\u00e7as na distribui\u00e7\u00e3o e avan\u00e7o da concorr\u00eancia pressionam a\u00e7\u00f5es das farmac\u00eauticas e abrem oportunidades para fabricantes<\/p>\n\n\n\n<p>\ud83c\udf0a Rio ter\u00e1 virada no tempo e ressaca com ondas de at\u00e9 tr\u00eas metros de altura a partir desta segunda-feira (13), segundo o Centro de Opera\u00e7\u00f5es e Resili\u00eancia (COR) da Prefeitura do Rio, com base em um aviso emitido pela Marinha do Brasil; mudan\u00e7as nas condi\u00e7\u00f5es do tempo come\u00e7aram com \u00e1reas de instabilidade associadas a uma frente fria que aumentaram a nebulosidade sobre a capital<\/p>\n\n\n\n<p>\ud83d\ude9c Agroneg\u00f3cio: El Ni\u00f1o pode afetar oferta de mandioca e pressionar produtores e ind\u00fastrias; fen\u00f4meno clim\u00e1tico pode favorecer o avan\u00e7o de doen\u00e7as nas lavouras e reduzir a oferta de ra\u00edzes no Paran\u00e1, principal polo industrial de amido do Brasil<\/p>\n\n\n\n<p>\u271d\ufe0f\ud83d\udcfa Morre no Rio de Janeiro, aos 88 anos, o ator Rui Rezende, que marcou \u00e9poca em Roque Santeiro; ele fez fama na TV brasileira com o papel de Professor Astromar Junqueira, o lobisomem da novela Roque Santeiro nos anos 80; Rui morava desde 2019 no Retiro dos Artistas, em Jacarepagu\u00e1, mas passou os \u00faltimos dez dias internado no Hospital S\u00e3o Francisco na Provid\u00eancia de Deus, na Tijuca; a causa da morte n\u00e3o foi divulgada<\/p>\n\n\n\n<p>CI\u00caNCIA e TECNOLOGIA<\/p>\n\n\n\n<p>\ud83d\ude9c Nanotecnologia ganha espa\u00e7o no combate aos percevejos nas planta\u00e7\u00f5es de soja; estudo re\u00fane os avan\u00e7os mais recentes no combate \u00e0 principal praga da soja e aponta tend\u00eancias para o manejo do futuro<\/p>\n\n\n\n<p>\ud83d\udc65 Mais de 160 milh\u00f5es de metros c\u00fabicos de lava emergiram ap\u00f3s o fundo do Oceano \u00cdndico se abrir, criando uma nova estrutura geol\u00f3gica submarina; a erup\u00e7\u00e3o submarina permitiu que cientistas acompanhassem, praticamente em tempo real, a forma\u00e7\u00e3o de uma nova por\u00e7\u00e3o da crosta terrestre<\/p>\n\n\n\n<p>\ud83c\uddf8\ud83c\uddea\ud83d\udc3a Restos de lobos encontrados em uma pequena ilha da Su\u00e9cia est\u00e3o levando cientistas a rever o que se sabe sobre a rela\u00e7\u00e3o entre humanos e esses animais na pr\u00e9-hist\u00f3ria; as evid\u00eancias indicam que os lobos viviam pr\u00f3ximos de comunidades humanas h\u00e1 cerca de cinco mil anos, eram alimentados por elas e podem at\u00e9 ter recebido cuidados, mesmo sem apresentarem caracter\u00edsticas gen\u00e9ticas de c\u00e3es domesticados<\/p>\n\n\n\n<p>\ud83c\uddef\ud83c\uddf5\ud83d\ude80 Jap\u00e3o testa primeiro voo de foguete reutiliz\u00e1vel do pa\u00eds; RV-X decolou, fez movimentos no ar e pousou ap\u00f3s menos de um minuto em teste que busca diminuir custos de lan\u00e7amentos espaciais<\/p>\n\n\n\n<p>ESPORTES<\/p>\n\n\n\n<p>\u26bd Campeonato Brasileiro<br \/>S\u00e9rie B, 17\u00aa rodada:<br \/>Oper\u00e1rio-PR 2&#215;1 Novorizontino<br \/>Ava\u00ed 2&#215;0 N\u00e1utico<br \/>S\u00e3o Bernardo 2&#215;2 Cuiab\u00e1<br \/>Atl\u00e9tico-GO 1&#215;0 Fortaleza<br \/>CRB 2&#215;2 Goi\u00e1s<\/p>\n\n\n\n<p>\u26bd Fifa estuda aumento da Copa para 64 times e Gianni Infantino defende pre\u00e7os dos ingressos; na vis\u00e3o do presidente da entidade, a decis\u00e3o de aumentar sele\u00e7\u00f5es para essa Copa foi um &#8220;enorme sucesso&#8221;<\/p>\n\n\n\n<p>\ud83c\udfbe\ud83d\udc65 Luisa Stefani e a canadense Gabriela Dabrowski perdem a final de duplas e ficam com o vice em Wimbledon; dupla foi superada pela chinesa Guo Hanyu e a francesa Kristina Mladenovic, por 2 sets a 0, com parciais de 6\/3 e 7\/5; assim, tenista brasileira perde a chance de devolver pa\u00eds ao primeiro lugar das duplas no Grand Slam ingl\u00eas, 60 anos ap\u00f3s o \u00faltimo t\u00edtulo de Maria Esther Bueno na categoria<\/p>\n\n\n\n<p>\ud83c\udfbe\ud83c\udfc6 Jannik Sinner vence Alexander Zverev de virada e conquista o bicampeonato de Wimbledon; tenista italiano perde o primeiro set, reage e derrota o alem\u00e3o por 3 a 1 para levantar mais uma vez o trof\u00e9u no Grand Slam ingl\u00eas<\/p>\n\n\n\n<p>\ud83c\udf0d\ud83d\udcf0 NOT\u00cdCIAS INTERNACIONAIS<\/p>\n\n\n\n<p>\ud83c\uddfa\ud83c\udde6\ud83c\uddf7\ud83c\uddfa Drones inimigos ditam movimentos na guerra da Ucr\u00e2nia; a amea\u00e7a a\u00e9rea constante obriga soldados a esconderem obuseiros e adia miss\u00f5es de disparo na linha de frente<\/p>\n\n\n\n<p>\ud83c\uddfa\ud83c\udde6\ud83c\uddf7\ud83c\uddfa Ucr\u00e2nia afirma ter lan\u00e7ado novos ataques contra navios russos; ao todo, 14 embarca\u00e7\u00f5es foram atingidas, incluindo 10 petroleiros e quatro balsas<\/p>\n\n\n\n<p>\ud83c\uddfa\ud83c\udde6 Ucr\u00e2nia: Volodymyr Zelensky anuncia substitui\u00e7\u00e3o de primeira-ministra e reformas no governo; Yulia Svyrydenko foi nomeada em julho de 2025, ap\u00f3s um ano como vice-chefe do gabinete do presidente ucraniano<\/p>\n\n\n\n<p>\ud83c\uddfb\ud83c\udde6 Le\u00e3o XIV pede di\u00e1logo para fim de guerras no Oriente M\u00e9dio e na Ucr\u00e2nia; Papa apelou \u00e0 diplomacia para dissipar o que chamou de &#8220;ventos de guerra&#8221;<\/p>\n\n\n\n<p>\ud83c\uddf5\ud83c\uddf1 Pol\u00f4nia refor\u00e7a produ\u00e7\u00e3o de drones de ataque com guerra na fronteira; sistema a\u00e9reo n\u00e3o tripulado Hornet foi desenvolvido pelo grupo industrial privado Boryszew em parceria com o Instituto de Tecnologia da For\u00e7a A\u00e9rea (ITWL), apoiado pelo Estado<\/p>\n\n\n\n<p>\ud83c\uddeb\ud83c\uddf7 Le Pen lidera pesquisas para elei\u00e7\u00e3o de 2027 mesmo ap\u00f3s condena\u00e7\u00e3o; dois institutos mostram a l\u00edder da ultradireita \u00e0 frente no primeiro turno e como vencedora no segundo da elei\u00e7\u00e3o presidencial de 2025<\/p>\n\n\n\n<p>\ud83c\uddee\ud83c\uddf7 Explos\u00f5es s\u00e3o ouvidas pr\u00f3ximo ao Estreito de Ormuz, diz m\u00eddia iraniana; governador de Qeshm relata 10 a 11 ataques em meio a ru\u00eddos de explos\u00f5es perto do Estreito de Ormuz e Bandar Abbas<\/p>\n\n\n\n<p>\ud83c\uddee\ud83c\uddf7 M\u00eddia iraniana relata ataques contra v\u00e1rios locais no sul do Ir\u00e3; m\u00eddia iraniana relata investidas de &#8220;inimigo&#8221; em Hormozgan, mas autoria dos bombardeios n\u00e3o foi identificada<\/p>\n\n\n\n<p>\ud83c\uddee\ud83c\uddf7 Ir\u00e3 lan\u00e7a ataques contra instala\u00e7\u00f5es militares dos EUA no Kuwait e Bahrain; Guarda Revolucion\u00e1ria diz que ofensiva incluiu bases em dois pa\u00edses do Golfo e promete manter as a\u00e7\u00f5es de retalia\u00e7\u00e3o<\/p>\n\n\n\n<p>\ud83c\uddf0\ud83c\uddfc Kuwait diz que drones do Ir\u00e3 atingiram fronteiras e plataforma de petr\u00f3leo; Minist\u00e9rio da Defesa do pa\u00eds relata danos materiais e um ferido em opera\u00e7\u00e3o com drones neste domingo (12)<\/p>\n\n\n\n<p>\ud83c\udde7\ud83c\udde9\ud83c\udf28\ufe0f Fortes chuvas no sudeste de Bangladesh deixam ao menos 51 mortos; o mau tempo foi intensificado por uma depress\u00e3o na Ba\u00eda de Bengala, agravando as inunda\u00e7\u00f5es em toda a regi\u00e3o; mais de um milh\u00e3o de pessoas permanecem isoladas por conta do mau tempo<\/p>\n\n\n\n<p>\ud83c\uddf9\ud83c\udded\ud83d\udd25 Inc\u00eandio em pub na Tail\u00e2ndia deixa pelo menos 27 mortos, dizem autoridades; caso ocorreu nas primeiras horas desta segunda-feira (13) em Rong Beer Na Lat Phrao, em Bangkok, um local popular na regi\u00e3o norte da capital tailandesa<\/p>\n\n\n\n<p>\ud83c\uddfa\ud83c\uddf8\ud83c\uddee\ud83c\uddf7 EUA concluem nova onda de ataques no Ir\u00e3, atingindo &#8220;dezenas&#8221; de alvos; segundo o CENTCOM, a opera\u00e7\u00e3o teve como objetivo reduzir a capacidade de Teer\u00e3 de amea\u00e7ar a navega\u00e7\u00e3o no Estreito de Ormuz<\/p>\n\n\n\n<p>\ud83c\uddfa\ud83c\uddf8\ud83c\uddf7\ud83c\uddfa Trump aumenta press\u00e3o sobre Putin por acordo com a Ucr\u00e2nia; mudan\u00e7a de postura dos EUA e apoio da Otan elevam custos da guerra para a R\u00fassia; risco nuclear \u00e9 avaliado por especialistas<\/p>\n\n\n\n<p>\ud83c\uddf2\ud83c\uddfd Batalha interna pelo Cartel de Sinaloa agrava crise de viol\u00eancia no M\u00e9xico; ap\u00f3s captura de \u201cEl Mayo\u201d Zambada, fac\u00e7\u00f5es \u201cLos Mayos\u201d e \u201cLos Chapitos\u201d travam disputa pelo comando do grupo<\/p>\n\n\n\n<p>\ud83c\uddf2\ud83c\uddfd Acidente em rodovia no M\u00e9xico deixa ao menos 10 mortos e v\u00e1rios feridos; colis\u00e3o ocorreu em uma estrada entre Guadalajara e Tepic e provocou um inc\u00eandio que destruiu cinco ve\u00edculos; causas ainda s\u00e3o investigadas<\/p>\n\n\n\n<p>\ud83c\udde8\ud83c\udde6 Troca de tiros em rua de festival latino em Toronto, no Canad\u00e1, deixa dois mortos; ao todo, seis pessoas foram baleadas; quatro foram levadas ao hospital com ferimentos graves<\/p>\n\n\n\n<p>\ud83c\uddfb\ud83c\uddea\ud83d\udc65 N\u00famero de mortos nos terremotos da Venezuela sobre para 4.490; segundo o presidente da Assembleia Nacional, Jorge Rodr\u00edguez, n\u00famero de feridos se manteve em 16.740 e o n\u00famero de desabrigados \u00e9 de cerca de 18 mil<\/p>\n\n\n\n<p>\ud83c\uddfb\ud83c\uddea\ud83c\udde8\ud83c\uddf4 Ditadura da Venezuela rejeita ajuda oferecida pelo presidente eleito da Col\u00f4mbia, Abelardo de la Espriella, ap\u00f3s terremotos que atingiram o pa\u00eds em 24 de junho; a resposta oficial ocorreu por meio de nota, na qual Caracas afirmou ter recebido \u201ccom estranheza\u201d as declara\u00e7\u00f5es do futuro mandat\u00e1rio colombiano e reiterou que a recupera\u00e7\u00e3o das regi\u00f5es afetadas \u00e9 uma responsabilidade \u201cexclusiva\u201d do estado venezuelano<\/p>\n\n\n\n<p>\ud83c\udde8\ud83c\uddf1 Integrante da Marinha do Chile atropela e mata seis pessoas em feira; motorista, que estava fora de servi\u00e7o, invadiu feira livre em Vi\u00f1a Del Mar com ve\u00edculo particular em alta velocidade<\/p>\n\n\n\n<p>\ud83c\udfa5\u271d\ufe0f Morre aos 78 anos Sam Neill, astro neozeland\u00eas de &#8220;Jurassic Park&#8221;; morte ocorre ap\u00f3s o ator se recuperar de um c\u00e2ncer; fam\u00edlia informou que a perda foi &#8220;repentina e inesperada&#8221;; em cinco d\u00e9cadas de carreira, Neill protagonizou dezenas de obras cinematogr\u00e1ficas, incluindo os filmes &#8220;O Piano&#8221;, &#8220;A Ca\u00e7ada ao Outubro Vermelho&#8221; e a s\u00e9rie &#8220;Peaky Blinders&#8221;<\/p>\n\n\n\n<p>\ud83c\udfa5\u271d\ufe0f Morre Wai Ching Ho, atriz que interpretou vil\u00e3 da Marvel, aos 82 anos; o an\u00fancio foi feito pelo ex-colega de elenco, Peter Shinkoda, em postagem nas redes sociais; ele publicou fotos da atriz e relembrou o per\u00edodo em que trabalharam juntos dentro e fora do set; ele divulgou a morte da atriz neste domingo (12) e revelou que a causa do falecimento foi um AVC (Acidente Vascular Cerebral); atriz ficou conhecida por viver Madame Gao em &#8220;Demolidor&#8221; e &#8220;Punho de Ferro&#8221;<\/p>\n\n\n\n<p>\ud83c\udf0d EVENTOS HIST\u00d3RICOS DO DIA<\/p>\n\n\n\n<p>-1249: Coroa\u00e7\u00e3o de Alexandre III como Rei da Esc\u00f3cia<\/p>\n\n\n\n<p>-1640: No Brasil, os jesu\u00edtas acabaram expulsos do Col\u00e9gio em S\u00e3o Paulo por pretenderem ver obedecido o breve apost\u00f3lico do Papa sobre a liberdade dos \u00edndios<\/p>\n\n\n\n<p>-1878: Tratado de Berlim: as pot\u00eancias europeias redesenham o mapa dos Balc\u00e3s, e S\u00e9rvia, Montenegro e Rom\u00eania tornam-se completamente independentes do Imp\u00e9rio Otomano<\/p>\n\n\n\n<p>-1901: Santos Dumont contorna a Torre Eiffel, em Paris (Fran\u00e7a), com um dirig\u00edvel<\/p>\n\n\n\n<p>-1917: Ocorre a terceira das seis apari\u00e7\u00f5es da Virgem Maria \u00e0s tr\u00eas crian\u00e7as de F\u00e1tima, Portugal<\/p>\n\n\n\n<p>-1919: O dirig\u00edvel brit\u00e2nico R34 pousa em Norfolk, na Inglaterra, completando a primeira viagem de volta atrav\u00e9s do Atl\u00e2ntico em 182 horas de voo<\/p>\n\n\n\n<p>-1923: O Letreiro de Hollywood \u00e9 oficialmente inaugurado nas colinas de Los Angeles, nos Estados Unidos<\/p>\n\n\n\n<p>-1930: Come\u00e7a a primeira Copa do Mundo da FIFA no Uruguai<\/p>\n\n\n\n<p>-1945: Projeto Manhattan: terminam os preparativos para a experi\u00eancia Trinity, considerada o in\u00edcio da Era Nuclear<\/p>\n\n\n\n<p>-1985: O concerto beneficente Live Aid, com o objetivo de arrecadar fundos a fim de acabar com a fome na Eti\u00f3pia, acontece em Londres e na Filad\u00e9lfia, bem como em outros locais como Moscou e Sydney<\/p>\n\n\n\n<p>-1990: Institu\u00eddo no Brasil o Estatuto da Crian\u00e7a e do Adolescente, Lei n\u00b0 8069\/90<\/p>\n\n\n\n<p>-2007: Iniciam-se os XV Jogos Pan-Americanos, realizados no Rio de Janeiro<\/p>\n\n\n\n<p>-2014: A Alemanha vence a Copa do Mundo Fifa 2014, no Brasil, derrotando a Argentina na final ap\u00f3s vit\u00f3ria por 1 a 0 na prorroga\u00e7\u00e3o<\/p>\n\n\n\n<p>-2024: Donald Trump, ent\u00e3o candidato \u00e0 presid\u00eancia dos Estados Unidos, sofre uma tentativa de assassinato em com\u00edcio na Pensilv\u00e2nia<\/p>\n\n\n\n<p>Essas s\u00e3o algumas not\u00edcias do dia \u2705<br \/>Autor: Roberto Vieira Filho \ud83c\udde7\ud83c\uddf7\ud83c\udf0e<br \/>Bom Dia!!! \ud83d\udc4d\ud83c\udffc\ud83d\ude09<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2705 NOT\u00cdCIAS DO DIA &#8211; ANO 10 n\u00b0 3523Dia 13 de Julho de 2026, Segunda-Feira DATAS COMEMORATIVASDia do CantorDia dos Compositores e Cantores SertanejosDia do Engenheiro de SaneamentoDia Mundial de Conscientiza\u00e7\u00e3o sobre o TDAHDia Mundial do Rock TEMPERATURA E INDICADORES FINANCEIROS\u26c5 M\u00edn 24\u2070 M\u00e1x 31\u2070 (Bel\u00e9m-PA)\ud83d\udcb5 D\u00f3lar Com \u2b07\ufe0f 0,28% R$ 5,10\ud83d\udcb6 Euro \u2b07\ufe0f 0,38% [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-172401","post","type-post","status-publish","format-standard","hentry","category-engracadas"],"_links":{"self":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts\/172401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/comments?post=172401"}],"version-history":[{"count":1,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts\/172401\/revisions"}],"predecessor-version":[{"id":172402,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts\/172401\/revisions\/172402"}],"wp:attachment":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/media?parent=172401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/categories?post=172401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/tags?post=172401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}