
{"id":84485,"date":"2019-07-29T10:04:02","date_gmt":"2019-07-29T13:04:02","guid":{"rendered":"https:\/\/www.largadoemguarapari.com.br\/13largado\/?p=84485"},"modified":"2019-07-29T10:04:02","modified_gmt":"2019-07-29T13:04:02","slug":"frase-do-dia-2075","status":"publish","type":"post","link":"https:\/\/www.largadoemguarapari.com.br\/13largado\/frase-do-dia-2075\/","title":{"rendered":"FRASE DO DIA"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\">\u2018Amaz\u00f4nia pertence ao povo brasileiro\u2019, diz Bolsonaro em discurso no Rio<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">\n\n\u201cO Brasil \u00e9 nosso, a Amaz\u00f4nia \u00e9 nossa, a Presid\u00eancia \u00e9 do povo brasileiro, povo esse ao qual eu devo lealdade absoluta. Pela primeira vez na hist\u00f3ria do Brasil temos um presidente que est\u00e1 honrando e cumprindo o que prometeu durante a campanha\u201d, declarou.\n\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2018Amaz\u00f4nia pertence ao povo brasileiro\u2019, diz Bolsonaro em discurso no Rio \u201cO Brasil \u00e9 nosso, a Amaz\u00f4nia \u00e9 nossa, a Presid\u00eancia \u00e9 do povo brasileiro, povo esse ao qual eu devo lealdade absoluta. Pela primeira vez na hist\u00f3ria do Brasil temos um presidente que est\u00e1 honrando e cumprindo o que prometeu durante a campanha\u201d, declarou.<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-84485","post","type-post","status-publish","format-standard","hentry","category-engracadas"],"_links":{"self":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts\/84485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/comments?post=84485"}],"version-history":[{"count":1,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts\/84485\/revisions"}],"predecessor-version":[{"id":84486,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/posts\/84485\/revisions\/84486"}],"wp:attachment":[{"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/media?parent=84485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/categories?post=84485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.largadoemguarapari.com.br\/13largado\/wp-json\/wp\/v2\/tags?post=84485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}